{"id":77892,"date":"2025-12-24T16:05:49","date_gmt":"2025-12-24T15:05:49","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=77892"},"modified":"2026-03-02T15:23:29","modified_gmt":"2026-03-02T14:23:29","slug":"novo-projeto-rentabilidade-anual-de-105-na-galiza","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/","title":{"rendered":"Rentabilidade anual de 10,5% na Galiza"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"77892\" class=\"elementor elementor-77892 elementor-77808\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3f1c6f9b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f1c6f9b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68f62f4d\" data-id=\"68f62f4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95bc33d elementor-widget elementor-widget-text-editor\" data-id=\"95bc33d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>Apresentamos <strong><a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000438\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=auria_1&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto Auria<\/a><\/strong>, um novo projeto de d\u00edvida para financiar o desenvolvimento de dois ativos na Galiza, em Ourense e Cangas. A opera\u00e7\u00e3o oferece uma <strong>rentabilidade anual fixa de 10,5%<\/strong>, com um montante de empr\u00e9stimo de at\u00e9 <strong>1.010.000 \u20ac<\/strong> em um \u00fanico tranche.<\/p>\n<p> <\/p>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_GW6_bOHkQkKQt1xyjbhQRg\" target=\"_blank\" rel=\"noreferrer noopener\">Webinar<\/a>:<\/strong> sexta-feira, 26 de dezembro \u00e0s 12:00 (UTC+1)<\/li>\n \n<li><strong>Abertura:<\/strong> segunda-feira, 29 de dezembro \u00e0s 12:00 (UTC+1)<\/li>\n<\/ul>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Dois ativos em Ourense e Cangas<\/h2>\n<p> <\/p>\n<p><strong>Projeto Auria<\/strong> consiste na concess\u00e3o de um empr\u00e9stimo para financiar parcialmente o <strong>cambio de uso de terci\u00e1rio para residencial<\/strong> e os <strong>custos de reforma<\/strong> de dois ativos:<br \/>Em Ourense, o projeto contempla a convers\u00e3o de um escrit\u00f3rio em mezanino para residencial, para desenvolver 8 apartamentos de 1 e 2 quartos na <strong>R\u00faa Valle Incl\u00e1n 1<\/strong>. A licen\u00e7a de mudan\u00e7a de uso e reforma de obra maior foi concedida em novembro de 2025, e prev\u00ea-se iniciar as obras ap\u00f3s a compra do ativo, com prazo estimado de 12 meses. A comercializa\u00e7\u00e3o est\u00e1 prevista ap\u00f3s a compra.<br \/>Em Cangas (Pontevedra), est\u00e1 a ser desenvolvido o cambio de uso de um espa\u00e7o comercial para residencial, para construir 3 apartamentos de 1 e 2 quartos na <strong>Avenida Ourense 19<\/strong>. O ativo foi adquirido em julho de 2024, a licen\u00e7a concedida em novembro de 2024, e as obras \u2014 iniciadas em julho de 2025 \u2014 encontram-se aproximadamente <strong>50% conclu\u00eddas<\/strong>, com prazo estimado de 6 meses at\u00e9 a conclus\u00e3o. Atualmente, <strong>2 das 3 unidades j\u00e1 est\u00e3o vendidas<\/strong>.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Um gestor local com experi\u00eancia em reformas e mudan\u00e7as de uso<\/h2>\n<p> <\/p>\n<p>O gestor do <strong><a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000438\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=auria_2&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto Auria<\/a><\/strong> \u00e9 a <strong>Ledicia Real Estate<\/strong>, grupo imobili\u00e1rio galego fundado em 2022 por profissionais com mais de 20 anos de experi\u00eancia no <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/11\/30\/tendenze-del-settore-immobiliare-verso-il-2026\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=setor_imobiliario&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">setor imobili\u00e1rio<\/a> e financeiro. Nos \u00faltimos anos especializou-se em reformas integrais de edif\u00edcios residenciais, mudan\u00e7as de uso e oportunidades com valor acrescentado na <a href=\"https:\/\/www.eleconomista.es\/economia\/noticias\/13375585\/05\/25\/el-patrimonio-en-fondos-de-inversion-en-galicia-crecio-un-195-en-2024-hasta-los-15451-millones.html\" target=\"_blank\" rel=\"noreferrer noopener\">Galiza<\/a>.<\/p>\n<p> <\/p>\n<p><strong>Estrutura do empr\u00e9stimo<\/strong><br \/>A opera\u00e7\u00e3o \u00e9 estruturada via d\u00edvida, mediante concess\u00e3o de um empr\u00e9stimo hipotec\u00e1rio em um \u00fanico tranche, no valor de at\u00e9 <strong>1.010.000 \u20ac<\/strong>, financiado na totalidade pelos investidores da Urbanitae. O empr\u00e9stimo oferece uma <strong>taxa de juro anual fixa simples de 10,5%<\/strong>, com prazo de <strong>18 meses<\/strong> e possibilidade de extens\u00e3o de <strong>6 meses<\/strong>. O capital e os juros ser\u00e3o pagos no vencimento, com <strong>retorno m\u00ednimo garantido<\/strong> equivalente a <strong>12 meses de juros<\/strong>.<br \/>A parte do empr\u00e9stimo destinada a financiar as obras ser\u00e1 disponibilizada mediante <strong>certifica\u00e7\u00f5es mensais<\/strong>, validadas por um <strong>Project Monitor<\/strong> independente. A amortiza\u00e7\u00e3o antecipada total \u00e9 permitida em qualquer momento, respeitando o retorno m\u00ednimo indicado.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Garantias do projeto<\/h2>\n<p> <\/p>\n<p>O empr\u00e9stimo contar\u00e1 com v\u00e1rias garantias para os investidores:<\/p>\n<p> <\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Hipoteca de primeiro grau<\/strong> sobre os ativos.<\/li>\n \n<li><strong>Penhor de primeiro grau<\/strong> sobre as a\u00e7\u00f5es e contas banc\u00e1rias da sociedade ve\u00edculo.<\/li>\n \n<li><strong>Cash sweep<\/strong> das receitas futuras geradas pelas vendas.<\/li>\n<\/ul>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Quando recuperarei o dinheiro investido?<\/h2>\n<p> <\/p>\n<p>O prazo estimado do <strong>Projeto Auria<\/strong> \u00e9 de 18 meses, com poss\u00edvel extens\u00e3o de 6 meses ao m\u00eas 18. O calend\u00e1rio previsto:<\/p>\n<p> <\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Janeiro de 2026:<\/strong> concess\u00e3o do empr\u00e9stimo e formaliza\u00e7\u00e3o da compra do ativo em Ourense.<\/li>\n \n<li><strong>Primeiro trimestre de 2026:<\/strong> in\u00edcio das obras de reforma e comercializa\u00e7\u00e3o em Ourense e continua\u00e7\u00e3o das obras em Cangas.<\/li>\n \n<li><strong>Segundo trimestre de 2026:<\/strong> conclus\u00e3o das obras e entrega das unidades em Cangas.<\/li>\n \n<li><strong>Segundo trimestre de 2027:<\/strong> conclus\u00e3o das obras e entrega das unidades em Ourense e reembolso do empr\u00e9stimo.<\/li>\n<\/ul>\n<p> <\/p>\n<p>Neste v\u00eddeo explicamos os pontos fundamentais do projeto.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a0d2cbf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a0d2cbf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e84d3e9\" data-id=\"e84d3e9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd198af elementor-widget elementor-widget-video\" data-id=\"bd198af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/KsbAQpCQhRg&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5df2574 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5df2574\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10bc60b\" data-id=\"10bc60b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ab74e0 elementor-widget elementor-widget-text-editor\" data-id=\"9ab74e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"wp-block-heading\"><\/h2>\n<p>Apresentamos <strong><a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000438\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=auria_1&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto Auria<\/a><\/strong>, um novo projeto de d\u00edvida para financiar o desenvolvimento de dois ativos na Galiza, em Ourense e Cangas. A opera\u00e7\u00e3o oferece uma <strong>rentabilidade anual fixa de 10,5%<\/strong>, com um montante de empr\u00e9stimo de at\u00e9 <strong>1.010.000 \u20ac<\/strong> em um \u00fanico tranche.<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_GW6_bOHkQkKQt1xyjbhQRg\" target=\"_blank\" rel=\"noreferrer noopener\">Webinar<\/a>:<\/strong> sexta-feira, 26 de dezembro \u00e0s 12:00 (UTC+1)<\/li>\n \n<li><strong>Abertura:<\/strong> segunda-feira, 29 de dezembro \u00e0s 12:00 (UTC+1)<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<h2 class=\"wp-block-heading\">Dois ativos em Ourense e Cangas<\/h2>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p><strong>Projeto Auria<\/strong> consiste na concess\u00e3o de um empr\u00e9stimo para financiar parcialmente o <strong>cambio de uso de terci\u00e1rio para residencial<\/strong> e os <strong>custos de reforma<\/strong> de dois ativos:<br \/>Em Ourense, o projeto contempla a convers\u00e3o de um escrit\u00f3rio em mezanino para residencial, para desenvolver 8 apartamentos de 1 e 2 quartos na <strong>R\u00faa Valle Incl\u00e1n 1<\/strong>. A licen\u00e7a de mudan\u00e7a de uso e reforma de obra maior foi concedida em novembro de 2025, e prev\u00ea-se iniciar as obras ap\u00f3s a compra do ativo, com prazo estimado de 12 meses. A comercializa\u00e7\u00e3o est\u00e1 prevista ap\u00f3s a compra.<br \/>Em Cangas (Pontevedra), est\u00e1 a ser desenvolvido o cambio de uso de um espa\u00e7o comercial para residencial, para construir 3 apartamentos de 1 e 2 quartos na <strong>Avenida Ourense 19<\/strong>. O ativo foi adquirido em julho de 2024, a licen\u00e7a concedida em novembro de 2024, e as obras \u2014 iniciadas em julho de 2025 \u2014 encontram-se aproximadamente <strong>50% conclu\u00eddas<\/strong>, com prazo estimado de 6 meses at\u00e9 a conclus\u00e3o. Atualmente, <strong>2 das 3 unidades j\u00e1 est\u00e3o vendidas<\/strong>.<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<h2 class=\"wp-block-heading\">Um gestor local com experi\u00eancia em reformas e mudan\u00e7as de uso<\/h2>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>O gestor do <strong><a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000438\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=auria_2&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto Auria<\/a><\/strong> \u00e9 a <strong>Ledicia Real Estate<\/strong>, grupo imobili\u00e1rio galego fundado em 2022 por profissionais com mais de 20 anos de experi\u00eancia no <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/11\/30\/tendenze-del-settore-immobiliare-verso-il-2026\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=setor_imobiliario&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">setor imobili\u00e1rio<\/a> e financeiro. Nos \u00faltimos anos especializou-se em reformas integrais de edif\u00edcios residenciais, mudan\u00e7as de uso e oportunidades com valor acrescentado na <a href=\"https:\/\/www.eleconomista.es\/economia\/noticias\/13375585\/05\/25\/el-patrimonio-en-fondos-de-inversion-en-galicia-crecio-un-195-en-2024-hasta-los-15451-millones.html\" target=\"_blank\" rel=\"noreferrer noopener\">Galiza<\/a>.<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p><strong>Estrutura do empr\u00e9stimo<\/strong><br \/>A opera\u00e7\u00e3o \u00e9 estruturada via d\u00edvida, mediante concess\u00e3o de um empr\u00e9stimo hipotec\u00e1rio em um \u00fanico tranche, no valor de at\u00e9 <strong>1.010.000 \u20ac<\/strong>, financiado na totalidade pelos investidores da Urbanitae. O empr\u00e9stimo oferece uma <strong>taxa de juro anual fixa simples de 10,5%<\/strong>, com prazo de <strong>18 meses<\/strong> e possibilidade de extens\u00e3o de <strong>6 meses<\/strong>. O capital e os juros ser\u00e3o pagos no vencimento, com <strong>retorno m\u00ednimo garantido<\/strong> equivalente a <strong>12 meses de juros<\/strong>.<br \/>A parte do empr\u00e9stimo destinada a financiar as obras ser\u00e1 disponibilizada mediante <strong>certifica\u00e7\u00f5es mensais<\/strong>, validadas por um <strong>Project Monitor<\/strong> independente. A amortiza\u00e7\u00e3o antecipada total \u00e9 permitida em qualquer momento, respeitando o retorno m\u00ednimo indicado.<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<h2 class=\"wp-block-heading\">Garantias do projeto<\/h2>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>O empr\u00e9stimo contar\u00e1 com v\u00e1rias garantias para os investidores:<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<ul class=\"wp-block-list\">\n<li><strong>Hipoteca de primeiro grau<\/strong> sobre os ativos.<\/li>\n \n<li><strong>Penhor de primeiro grau<\/strong> sobre as a\u00e7\u00f5es e contas banc\u00e1rias da sociedade ve\u00edculo.<\/li>\n \n<li><strong>Cash sweep<\/strong> das receitas futuras geradas pelas vendas.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<h2 class=\"wp-block-heading\">Quando recuperarei o dinheiro investido?<\/h2>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>O prazo estimado do <strong>Projeto Auria<\/strong> \u00e9 de 18 meses, com poss\u00edvel extens\u00e3o de 6 meses ao m\u00eas 18. O calend\u00e1rio previsto:<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<ul class=\"wp-block-list\">\n<li><strong>Janeiro de 2026:<\/strong> concess\u00e3o do empr\u00e9stimo e formaliza\u00e7\u00e3o da compra do ativo em Ourense.<\/li>\n \n<li><strong>Primeiro trimestre de 2026:<\/strong> in\u00edcio das obras de reforma e comercializa\u00e7\u00e3o em Ourense e continua\u00e7\u00e3o das obras em Cangas.<\/li>\n \n<li><strong>Segundo trimestre de 2026:<\/strong> conclus\u00e3o das obras e entrega das unidades em Cangas.<\/li>\n \n<li><strong>Segundo trimestre de 2027:<\/strong> conclus\u00e3o das obras e entrega das unidades em Ourense e reembolso do empr\u00e9stimo.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>Neste v\u00eddeo explicamos os pontos fundamentais do projeto.<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<h2 class=\"wp-block-heading\">Fatores-chave para investir<\/h2>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>Resumo dos pontos fortes do <strong><a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000438\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=auria_3&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto Auria<\/a><\/strong>:<\/p>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<ul class=\"wp-block-list\">\n<li><strong>Dois ativos em Ourense e Cangas<\/strong>, com mudan\u00e7a de uso para residencial e reforma integral.<\/li>\n \n<li>Licen\u00e7as de mudan\u00e7a de uso e obra concedidas para ambos os projetos.<\/li>\n \n<li>Tra\u00e7\u00e3o comercial em Cangas, com <strong>2 das 3 unidades vendidas<\/strong> e obra <strong>50% conclu\u00edda<\/strong>.<\/li>\n \n<li><strong>Rentabilidade anual fixa de 10,5%<\/strong>, com retorno m\u00ednimo equivalente a 12 meses de juros.<\/li>\n \n<li><strong><a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/05\/26\/emprestimo-com-garantia-hipotecaria-o-que-e-e-porque-e-essencial-no-investimento-imobiliario\/?utm_source=blog_pt&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1225&amp;utm_term=garantia_hipotecaria_primeiro_grau&amp;utm_content=pt_proyecto_auria\" target=\"_blank\" rel=\"noreferrer noopener sponsored nofollow\">Garantia hipotec\u00e1ria de primeiro grau<\/a><\/strong> e pacote de garantias associado ao empr\u00e9stimo.<\/li>\n \n<li>Gest\u00e3o da comercializa\u00e7\u00e3o atrav\u00e9s da ag\u00eancia imobili\u00e1ria do grupo.<\/li>\n<\/ul>\n<h2 class=\"wp-block-heading\"> <\/h2>\n<p>Se tiver d\u00favidas sobre o <strong>Projeto Auria<\/strong>, pode coloc\u00e1-las no <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_GW6_bOHkQkKQt1xyjbhQRg\" target=\"_blank\" rel=\"noreferrer noopener\">webinar<\/a> de sexta-feira, 26 de dezembro, ou escrever para <strong><a href=\"mailto:contacto@urbanitae.com\" target=\"_blank\" rel=\"noreferrer noopener\">contacto@urbanitae.com<\/a><\/strong> ou ligar diretamente para <strong>(+34) 911 23 25 22<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Com garantias hipotec\u00e1rias de primeiro grau e um plano de reembolso claro, o Projeto Auria oferece aos investidores seguran\u00e7a e rentabilidade fixa.<\/p>\n","protected":false},"author":1,"featured_media":77890,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1079,1029,929],"tags":[1985,1983,2182,1984,2147,1014],"class_list":["post-77892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-divida","category-investimento-imobiliario-pt-pt","category-projetos","tag-crowdfunding-immobiliare-pt-pt","tag-investimento-imobiliario","tag-setor-imobiliario","tag-setor-residencial-pt-pt","tag-setor-residencial","tag-urbanitae-pt"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rentabilidade anual de 10,5% na Galiza<\/title>\n<meta name=\"description\" content=\"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investir na Galiza com rentabilidade fixa de 10,5%\" \/>\n<meta property=\"og:description\" content=\"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-24T15:05:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T14:23:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Rentabilidade anual de 10,5% na Galiza\",\"datePublished\":\"2025-12-24T15:05:49+00:00\",\"dateModified\":\"2026-03-02T14:23:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/\"},\"wordCount\":1250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp\",\"keywords\":[\"crowdfunding immobiliare\",\"investimento imobili\u00e1rio\",\"setor imobili\u00e1rio\",\"setor residencial\",\"setor residencial\",\"Urbanitae\"],\"articleSection\":[\"D\u00edvida\",\"Investimento imobili\u00e1rio\",\"Projetos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/\",\"name\":\"Rentabilidade anual de 10,5% na Galiza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp\",\"datePublished\":\"2025-12-24T15:05:49+00:00\",\"dateModified\":\"2026-03-02T14:23:29+00:00\",\"description\":\"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp\",\"width\":1400,\"height\":735},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/12\\\/24\\\/novo-projeto-rentabilidade-anual-de-105-na-galiza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rentabilidade anual de 10,5% na Galiza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Investimento imobili\u00e1rio ao alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rentabilidade anual de 10,5% na Galiza","description":"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/","og_locale":"pt_PT","og_type":"article","og_title":"Investir na Galiza com rentabilidade fixa de 10,5%","og_description":"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.","og_url":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/","og_site_name":"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-12-24T15:05:49+00:00","article_modified_time":"2026-03-02T14:23:29+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Escrito por":"Equipo Urbanitae","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Rentabilidade anual de 10,5% na Galiza","datePublished":"2025-12-24T15:05:49+00:00","dateModified":"2026-03-02T14:23:29+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/"},"wordCount":1250,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp","keywords":["crowdfunding immobiliare","investimento imobili\u00e1rio","setor imobili\u00e1rio","setor residencial","setor residencial","Urbanitae"],"articleSection":["D\u00edvida","Investimento imobili\u00e1rio","Projetos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/","url":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/","name":"Rentabilidade anual de 10,5% na Galiza","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp","datePublished":"2025-12-24T15:05:49+00:00","dateModified":"2026-03-02T14:23:29+00:00","description":"Investir na Galiza com o Projeto Auria: rentabilidade fixa de 10,5% e garantias hipotec\u00e1rias de primeiro grau.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/\u00a1Nuevo-proyecto-Rentabilidad-105-anual-en-Galicia.webp","width":1400,"height":735},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/12\/24\/novo-projeto-rentabilidade-anual-de-105-na-galiza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Rentabilidade anual de 10,5% na Galiza"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Investimento imobili\u00e1rio ao alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/pt-pt\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/77892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=77892"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/77892\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media\/77890"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=77892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=77892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=77892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}