{"id":62874,"date":"2025-04-29T13:50:45","date_gmt":"2025-04-29T11:50:45","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=62874"},"modified":"2025-04-29T16:46:37","modified_gmt":"2025-04-29T14:46:37","slug":"navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/","title":{"rendered":"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na Urbanitae, insistimos sempre que todo o investimento envolve riscos e que, embora fa\u00e7amos tudo o que est\u00e1 ao nosso alcance para minimizar os imprevistos, n\u00e3o podemos garantir uma rentabilidade espec\u00edfica. O caso do projeto <a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000139\">Navas de Tolosa<\/a>, em Barcelona, cuja liquida\u00e7\u00e3o foi recentemente conclu\u00edda, ilustra bem esta realidade e demonstra tamb\u00e9m como, com uma gest\u00e3o proactiva e focada na prote\u00e7\u00e3o dos interesses dos investidores, \u00e9 poss\u00edvel obter resultados positivos mesmo em contextos adversos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto, financiado em dezembro de 2021, consistia no desenvolvimento de um edif\u00edcio com 15 habita\u00e7\u00f5es, um espa\u00e7o comercial e 16 lugares de estacionamento. Inicialmente, previa-se um prazo de 22 meses e uma rentabilidade estimada de 29,9% (com uma TIR de 15,3%). No final, o projeto foi encerrado com um retorno bruto de 16,2% e uma TIR de 4,7% ao longo de 39 meses.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que aconteceu?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O desenvolvimento do projeto foi afetado por uma s\u00e9rie de circunst\u00e2ncias dif\u00edceis de prever no momento do financiamento:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Aumento dos custos de constru\u00e7\u00e3o:<\/strong> A adjudica\u00e7\u00e3o da obra coincidiu com um per\u00edodo de forte aumento de pre\u00e7os e escassez de materiais em 2022. O custo final da constru\u00e7\u00e3o foi 23% superior ao estimado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Urg\u00eancia no arranque das obras:<\/strong> Para evitar que a licen\u00e7a de constru\u00e7\u00e3o expirasse \u2013 o que obrigaria a destinar 30% do edif\u00edcio a habita\u00e7\u00e3o de prote\u00e7\u00e3o oficial \u2013 foi necess\u00e1rio iniciar rapidamente as obras, priorizando tarefas como movimenta\u00e7\u00e3o de terras e funda\u00e7\u00f5es. Isto reduziu a margem de negocia\u00e7\u00e3o com fornecedores e construtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Contexto econ\u00f3mico adverso:<\/strong> Durante a fase de comercializa\u00e7\u00e3o, o aumento das taxas de juro e a incerteza regulat\u00f3ria (especialmente em torno do golden visa) desaceleraram as vendas. No final das obras, mais de metade das habita\u00e7\u00f5es ainda n\u00e3o estavam vendidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Custos financeiros e comerciais mais elevados:<\/strong> Devido \u00e0 conjuntura econ\u00f3mica, o custo do empr\u00e9stimo ao promotor aumentou para 5,5% de juro, em compara\u00e7\u00e3o com os 2,5% inicialmente previstos. Al\u00e9m disso, foi necess\u00e1rio refor\u00e7ar os esfor\u00e7os de marketing e aumentar as comiss\u00f5es dos agentes imobili\u00e1rios para acelerar as vendas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que fez a Urbanitae<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar destes desafios, na Urbanitae trabalh\u00e1mos lado a lado com o promotor para encontrar solu\u00e7\u00f5es que minimizassem o impacto:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Otimiza\u00e7\u00e3o do projeto:<\/strong> Foram eliminadas obriga\u00e7\u00f5es como a de destinar um espa\u00e7o a centro de transforma\u00e7\u00e3o el\u00e9trica, convertendo-o em \u00e1rea vend\u00e1vel como habita\u00e7\u00e3o, o que permitiu aumentar os rendimentos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Flexibilidade na comercializa\u00e7\u00e3o:<\/strong> Foram adaptadas as estrat\u00e9gias de venda, incluindo a mobila\u00e7\u00e3o de algumas unidades e a colabora\u00e7\u00e3o com novas ag\u00eancias imobili\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Compra dos ativos em falta:<\/strong> Para encerrar a opera\u00e7\u00e3o, o promotor adquiriu os tr\u00eas lugares de estacionamento restantes ao pre\u00e7o publicado, evitando uma venda com desconto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gra\u00e7as a estas medidas, embora a rentabilidade n\u00e3o tenha sido a inicialmente prevista, o projeto <strong>foi encerrado com um retorno positivo de 16,2% para os investidores.<\/strong> N\u00e3o houve perdas de capital e conseguiu-se proteger o investimento num contexto bastante desafiante.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uma li\u00e7\u00e3o sobre risco e investimento imobili\u00e1rio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto <a href=\"https:\/\/urbanitae.com\/pt\/projeto\/P000139\" target=\"_blank\" rel=\"noreferrer noopener\">Navas de Tolosa<\/a> evidencia um dos princ\u00edpios fundamentais do investimento imobili\u00e1rio: <strong>a rentabilidade n\u00e3o \u00e9 garantida.<\/strong> Tal como em qualquer investimento, existem riscos que podem afetar os prazos e os lucros. No entanto, demonstra tamb\u00e9m que, ao contr\u00e1rio do que acontece nos mercados financeiros, <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/13\/porque-e-que-o-investimento-imobiliario-resiste-a-volatilidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">o setor imobili\u00e1rio \u00e9 muito mais resiliente<\/a>. E mostra, por fim, que uma gest\u00e3o profissional e ativa pode fazer a diferen\u00e7a, <strong>ajudando a preservar o capital e alcan\u00e7ar resultados positivos<\/strong> mesmo em cen\u00e1rios dif\u00edceis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na <a href=\"https:\/\/urbanitae.com\/pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Urbanitae<\/a>, continuamos comprometidos em oferecer aos nossos investidores toda a informa\u00e7\u00e3o de forma transparente, explicando tanto as oportunidades como os riscos de cada projeto. O nosso objetivo \u00e9 continuar a construir <strong>uma rela\u00e7\u00e3o de confian\u00e7a a longo prazo<\/strong>, baseada em informa\u00e7\u00e3o clara, sele\u00e7\u00e3o prudente de projetos e uma gest\u00e3o ativa orientada para a prote\u00e7\u00e3o dos interesses de quem confia em n\u00f3s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto Navas de Tolosa, em Barcelona, foi encerrado com uma rentabilidade total de 16% em 39 meses para os investidores da Urbanitae, com uma TIR de 4,7%.<\/p>\n","protected":false},"author":1,"featured_media":62853,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1059,929],"tags":[1961,1983,1001,1014],"class_list":["post-62874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equity-pt","category-projetos","tag-financiamento-colaborativo-de-capital","tag-investimento-imobiliario","tag-rentabilidade","tag-urbanitae-pt"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos<\/title>\n<meta name=\"description\" content=\"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Explicamos os resultados do projeto Navas de Tolosa\" \/>\n<meta property=\"og:description\" content=\"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T11:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T14:46:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos\",\"datePublished\":\"2025-04-29T11:50:45+00:00\",\"dateModified\":\"2025-04-29T14:46:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/\"},\"wordCount\":695,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"keywords\":[\"financiamento colaborativo de capital\",\"investimento imobili\u00e1rio\",\"rentabilidade\",\"Urbanitae\"],\"articleSection\":[\"Equity\",\"Projetos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/\",\"name\":\"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"datePublished\":\"2025-04-29T11:50:45+00:00\",\"dateModified\":\"2025-04-29T14:46:37+00:00\",\"description\":\"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"width\":1400,\"height\":735,\"caption\":\"Navas de Tolosa: rentabilidad positiva pese a los imprevistos. Navas de Tolosa: Positive returns despite unforeseen events. Navas de Tolosa : Rentabilit\u00e9 positive malgr\u00e9 les impr\u00e9vus. Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti. Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos. Navas de Tolosa: Positive Rendite trotz unvorhergesehener Ereignisse.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Investimento imobili\u00e1rio ao alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos","description":"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/","og_locale":"pt_PT","og_type":"article","og_title":"Explicamos os resultados do projeto Navas de Tolosa","og_description":"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.","og_url":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/","og_site_name":"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-04-29T11:50:45+00:00","article_modified_time":"2025-04-29T14:46:37+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Escrito por":"Equipo Urbanitae","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos","datePublished":"2025-04-29T11:50:45+00:00","dateModified":"2025-04-29T14:46:37+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/"},"wordCount":695,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","keywords":["financiamento colaborativo de capital","investimento imobili\u00e1rio","rentabilidade","Urbanitae"],"articleSection":["Equity","Projetos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/","url":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/","name":"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","datePublished":"2025-04-29T11:50:45+00:00","dateModified":"2025-04-29T14:46:37+00:00","description":"Explicamos porque a rentabilidade do projeto Navas de Tolosa n\u00e3o foi a esperada e o que fizemos para preservar o capital dos investidores.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","width":1400,"height":735,"caption":"Navas de Tolosa: rentabilidad positiva pese a los imprevistos. Navas de Tolosa: Positive returns despite unforeseen events. Navas de Tolosa : Rentabilit\u00e9 positive malgr\u00e9 les impr\u00e9vus. Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti. Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos. Navas de Tolosa: Positive Rendite trotz unvorhergesehener Ereignisse."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2025\/04\/29\/navas-de-tolosa-rentabilidade-positiva-apesar-dos-imprevistos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Investimento imobili\u00e1rio ao alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/pt-pt\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/62874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=62874"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/62874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media\/62853"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=62874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=62874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=62874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}