{"id":50315,"date":"2024-09-26T14:51:07","date_gmt":"2024-09-26T12:51:07","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=50315"},"modified":"2024-09-26T16:36:57","modified_gmt":"2024-09-26T14:36:57","slug":"e-necessario-aumentar-a-producao-de-habitacao-acessivel","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/","title":{"rendered":"&#8220;\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>O Grupo Salas \u00e9 o principal promotor de habita\u00e7\u00e3o social na Catalunha e um dos adjudicat\u00e1rios da terceira fase do Plano Vive da Comunidade de Madrid. Com mais de 30 anos de trajet\u00f3ria e uma equipa de mais de 270 profissionais, a empresa entregou mais de 4.000 habita\u00e7\u00f5es em todo o territ\u00f3rio nacional. Nesta entrevista, Manel Rodr\u00edguez, CEO e acionista do Grupo Salas, fala-nos da voca\u00e7\u00e3o social da promotora e do problema de acesso \u00e0 habita\u00e7\u00e3o, especialmente para os mais jovens, um dos maiores desafios do setor imobili\u00e1rio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quais foram os principais desafios que a promotora enfrentou nas suas tr\u00eas d\u00e9cadas no mercado imobili\u00e1rio?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo dos anos, o mercado imobili\u00e1rio sofreu mudan\u00e7as devido aos ciclos espec\u00edficos do setor, mas tamb\u00e9m foi impactado por flutua\u00e7\u00f5es econ\u00f3micas e financeiras, como o aumento das taxas de juro e a restri\u00e7\u00e3o do cr\u00e9dito hipotec\u00e1rio. \u00c0s vezes, fatores externos, como a pandemia, afetam-nos diretamente. De qualquer forma, a chave est\u00e1 em trabalhar sempre a longo prazo e ter for\u00e7a financeira para superar estes altos e baixos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Que tipo de projetos imobili\u00e1rios desenvolvem? O que vos diferencia da concorr\u00eancia?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Promovemos edif\u00edcios multifamiliares destinados \u00e0 primeira resid\u00eancia, para venda ou aluguer. Estamos especializados em habita\u00e7\u00e3o <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/01\/22\/um-impulso-para-o-aluguel-acessivel-na-espanha\/\" target=\"_blank\" rel=\"noreferrer noopener\">acess\u00edvel<\/a>, o que \u00e9 o nosso principal elemento diferenciador. N\u00e3o desenvolvemos habita\u00e7\u00e3o de luxo, moradias unifamiliares ou segundas resid\u00eancias. Estamos sempre no setor \u201ccentral\u201d do mercado, a classe m\u00e9dia que procura \u201ccasas para viver\u201d, e isso permite-nos garantir a procura, um aspeto chave do nosso posicionamento: temos sempre 90% das casas pr\u00e9-vendidas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Para quem est\u00e1 a pensar em comprar uma casa, diria que \u00e9 uma boa altura para o fazer ou para investir no setor imobili\u00e1rio?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comprar uma casa \u00e9 uma decis\u00e3o vital muito importante, que n\u00e3o deve ser vista apenas como um investimento financeiro, mas sim como um investimento pessoal. Se \u00e9 a casa de que a fam\u00edlia necessita, \u00e9 um bom investimento. A experi\u00eancia diz-nos que os investimentos imobili\u00e1rios s\u00e3o sempre um bom investimento patrimonial: \u00e9 um valor-ref\u00fagio que, nas localiza\u00e7\u00f5es de alta procura, aumenta sempre de pre\u00e7o. Mesmo ap\u00f3s a crise imobili\u00e1ria de 2007, as habita\u00e7\u00f5es em zonas de procura real recuperaram rapidamente o seu valor. As compras especulativas sem uma procura real por tr\u00e1s s\u00e3o outra quest\u00e3o!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todos os especialistas concordam que n\u00e3o h\u00e1 habita\u00e7\u00e3o suficiente para satisfazer a procura. Que medidas poderiam mitigar o problema?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este \u00e9 realmente um dos problemas mais complexos que a sociedade enfrentar\u00e1 nos pr\u00f3ximos anos. Todos os estudos demonstram que \u00e9 necess\u00e1rio duplicar a produ\u00e7\u00e3o, especialmente de habita\u00e7\u00e3o acess\u00edvel, n\u00e3o s\u00f3 para atender ao ritmo que a imigra\u00e7\u00e3o e a cria\u00e7\u00e3o de lares exigem, mas tamb\u00e9m para compensar o d\u00e9fice acumulado nos \u00faltimos cinco anos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para aumentar o ritmo de produ\u00e7\u00e3o, \u00e9 preciso conjugar v\u00e1rios fatores. Em primeiro lugar, a disponibilidade de terrenos urbanos. \u00c9 necess\u00e1rio considerar o aumento da popula\u00e7\u00e3o: por exemplo, a <a href=\"https:\/\/www.amb.cat\/s\/es\/web\/area-metropolitana\/area-metropolitana.html\" target=\"_blank\" rel=\"noreferrer noopener\">regi\u00e3o metropolitana de Barcelona<\/a> (que vai de Vilanova a Matar\u00f3, incluindo o Vall\u00e8s) j\u00e1 supera os 5 milh\u00f5es de pessoas. N\u00e3o podemos continuar a \u201cconsumir\u201d territ\u00f3rio onde ele n\u00e3o existe, por isso \u00e9 necess\u00e1rio densificar os planos urban\u00edsticos e agilizar o seu processamento. A administra\u00e7\u00e3o p\u00fablica deve atuar como agente urbanizador em grande escala, controlando as mais-valias, mas garantindo a disponibilidade de terrenos urbanos finalistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A administra\u00e7\u00e3o p\u00fablica, que controla todo o processo, deve tamb\u00e9m ser \u00e1gil, clara e est\u00e1vel. A regulamenta\u00e7\u00e3o urban\u00edstica, a fiscalidade, os alvar\u00e1s de constru\u00e7\u00e3o municipais, os registos cadastrais, os certificados de habitabilidade&#8230; O processo de promo\u00e7\u00e3o de habita\u00e7\u00e3o \u00e9 hiperregulado e o setor necessita de clareza, estabilidade e agilidade: um pacto de Estado transversal e de longo prazo para a promo\u00e7\u00e3o de habita\u00e7\u00e3o.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8220;\u00c9 necess\u00e1rio densificar os planos urban\u00edsticos e agilizar o seu processamento. A administra\u00e7\u00e3o p\u00fablica deve atuar como agente urbanizador em grande escala.&#8221;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A disponibilidade de financiamento \u00e9 tamb\u00e9m um fator importante. O setor imobili\u00e1rio consome muitos recursos financeiros. Desde a crise imobili\u00e1ria, o cr\u00e9dito foi reduzido, o que foi \u201csaud\u00e1vel\u201d, mas agora h\u00e1 uma grande capacidade de investimento e endividamento que precisa ser utilizada, com taxas de juro acess\u00edveis. Estou a falar de aumentar o cr\u00e9dito para promotores e aumentar as hipotecas para as fam\u00edlias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, \u00e9 importante destacar a capacidade produtiva. As casas t\u00eam de ser constru\u00eddas: n\u00e3o \u00e9 um processo te\u00f3rico, mas uma quest\u00e3o material que envolve muitos agentes. Quando falamos em duplicar a produ\u00e7\u00e3o, estamos a falar de pressionar um dos principais setores produtivos do PIB. Aqui precisamos de formar muita m\u00e3o-de-obra, que ter\u00e1 de ser estrangeira, precisamos de muita imigra\u00e7\u00e3o e, sobretudo, precisamos de apoiar a industrializa\u00e7\u00e3o do setor, que continua a ser um setor de produ\u00e7\u00e3o tradicional com meios obsoletos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/07\/16\/por-que-os-precos-das-casas-estao-a-subir-novamente-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">pre\u00e7os das habita\u00e7\u00f5es<\/a> e rendas est\u00e3o em n\u00edveis hist\u00f3ricos. Que medidas devem ser tomadas para melhorar o acesso \u00e0 habita\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As principais medidas devem visar aumentar a oferta, uma vez que o desequil\u00edbrio entre oferta e procura \u00e9 o que est\u00e1 a causar a crise atual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, para evitar uma escalada dos pre\u00e7os, somos favor\u00e1veis \u00e0 limita\u00e7\u00e3o do uso e da especula\u00e7\u00e3o econ\u00f3mica com as habita\u00e7\u00f5es destinadas a outras atividades econ\u00f3micas, como o turismo. Faz todo o sentido, porque se n\u00e3o os centros hist\u00f3ricos das cidades tur\u00edsticas se transformar\u00e3o em parques tem\u00e1ticos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&#8220;Os investimentos imobili\u00e1rios s\u00e3o sempre um bom investimento patrimonial, um valor-ref\u00fagio.&#8221;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Em paralelo, acreditamos que, de forma excecional e tempor\u00e1ria, enquanto se trabalha nesse aumento da produ\u00e7\u00e3o, algumas limita\u00e7\u00f5es tempor\u00e1rias possam ser implementadas, como, por exemplo, a limita\u00e7\u00e3o artificial das rendas, mas sempre de forma provis\u00f3ria. Temos de estar cientes de que as medidas para limitar artificialmente as rendas ser\u00e3o contraproducentes a m\u00e9dio e longo prazo, se n\u00e3o for corrigida a produ\u00e7\u00e3o de novas ofertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Resolver o problema do acesso \u00e0 habita\u00e7\u00e3o para os jovens \u00e9 precisamente um dos maiores desafios do setor imobili\u00e1rio. Esta situa\u00e7\u00e3o poderia ser resolvida com um maior parque de habita\u00e7\u00e3o p\u00fablica a pre\u00e7os acess\u00edveis. Que percentagem de habita\u00e7\u00e3o social gere a Salas atualmente?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/www.salas.plus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Grupo Salas<\/a> destina 50% da sua produ\u00e7\u00e3o a habita\u00e7\u00e3o social para arrendamento e outros 25% a habita\u00e7\u00e3o social para venda. Apenas 25% da nossa produ\u00e7\u00e3o \u00e9 habita\u00e7\u00e3o livre para venda. Acredito que muitos outros agentes precisam aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel, pois \u00e9 o que o pa\u00eds necessita. O nosso trabalho como promotores n\u00e3o \u00e9 apenas uma quest\u00e3o financeira: somos os fornecedores de um bem de primeira necessidade e temos uma responsabilidade social a este respeito. Na Salas, este princ\u00edpio orienta os nossos planos de crescimento e expans\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A empresa opera principalmente na Catalunha e Madrid. T\u00eam planos de expans\u00e3o para novas \u00e1reas geogr\u00e1ficas ou mercados?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Historicamente, tamb\u00e9m produzimos nas Baleares e esperamos voltar quando as condi\u00e7\u00f5es forem favor\u00e1veis \u00e0 produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel l\u00e1. Mais tarde, consideraremos a possibilidade de expandir o nosso modelo de produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel em grande escala para outros locais, mas por enquanto continuaremos a crescer na Catalunha e em Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Que tend\u00eancias acredita que definir\u00e3o o futuro do mercado de habita\u00e7\u00e3o em Espanha?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por um lado, veremos um aumento dos pre\u00e7os das habita\u00e7\u00f5es de mercado livre em \u00e1reas de alta procura, como Madrid, Barcelona, a Costa Mediterr\u00e2nea, as Ilhas e os centros urbanos das grandes cidades, transformando este mercado num bem de luxo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por outro lado, veremos uma produ\u00e7\u00e3o em grande escala de habita\u00e7\u00e3o social e acess\u00edvel, principalmente para arrendamento, que ser\u00e1 acess\u00edvel \u00e0queles que n\u00e3o podem comprar. Al\u00e9m disso, a produ\u00e7\u00e3o de outros modelos habitacionais, como coliving, flex living e <a href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/23\/o-senior-living-explora-oportunidades-de-investimento-na-espanha\/\" target=\"_blank\" rel=\"noreferrer noopener\">senior living<\/a>, tamb\u00e9m definir\u00e1 o futuro da habita\u00e7\u00e3o em Espanha. E, no setor produtivo, haver\u00e1 uma transforma\u00e7\u00e3o para a industrializa\u00e7\u00e3o e, paralelamente, para uma melhoria da sustentabilidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os estudos afirmam que \u00e9 necess\u00e1rio duplicar a produ\u00e7\u00e3o de habita\u00e7\u00e3o em Espanha&#8230; Mas porque n\u00e3o se faz? Fal\u00e1mos com o CEO do Grupo Salas sobre a situa\u00e7\u00e3o do setor imobili\u00e1rio.<\/p>\n","protected":false},"author":1,"featured_media":50340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[941],"tags":[973,1984,2147],"class_list":["post-50315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas-pt","tag-habitacao","tag-setor-residencial-pt-pt","tag-setor-residencial"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel&quot; - Urbanitae Blog<\/title>\n<meta name=\"description\" content=\"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es em Espanha? Como aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel? Entrevistamos o CEO da Salas aqui.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es?\" \/>\n<meta property=\"og:description\" content=\"Pergunt\u00e1mos ao CEO do Grupo Salas, Manel Rodr\u00edguez, sobre a situa\u00e7\u00e3o da habita\u00e7\u00e3o em Espanha e as medidas que poderiam ser tomadas para melhor\u00e1-la. Leia mais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-26T12:51:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T14:36:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"&#8220;\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel&#8221;\",\"datePublished\":\"2024-09-26T12:51:07+00:00\",\"dateModified\":\"2024-09-26T14:36:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/\"},\"wordCount\":1423,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/manel-salas-grupo-salas.webp\",\"keywords\":[\"habita\u00e7\u00e3o\",\"setor residencial\",\"setor residencial\"],\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/\",\"name\":\"\\\"\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel\\\" - Urbanitae Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/manel-salas-grupo-salas.webp\",\"datePublished\":\"2024-09-26T12:51:07+00:00\",\"dateModified\":\"2024-09-26T14:36:57+00:00\",\"description\":\"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es em Espanha? Como aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel? Entrevistamos o CEO da Salas aqui.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/manel-salas-grupo-salas.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/manel-salas-grupo-salas.webp\",\"width\":1400,\"height\":735,\"caption\":\"Manel Rodr\u00edguez, CEO del Grupo Salas. Manel Rodr\u00edguez, CEO of Grupo Salas. Manel Rodr\u00edguez, PDG de Grupo Salas. Manel Rodr\u00edguez, CEO di Grupo Salas. Manel Rodr\u00edguez, CEO do Grupo Salas. Manel Rodr\u00edguez, CEO von Grupo Salas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2024\\\/09\\\/26\\\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00ab\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Investimento imobili\u00e1rio ao alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel\" - Urbanitae Blog","description":"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es em Espanha? Como aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel? Entrevistamos o CEO da Salas aqui.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/","og_locale":"pt_PT","og_type":"article","og_title":"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es?","og_description":"Pergunt\u00e1mos ao CEO do Grupo Salas, Manel Rodr\u00edguez, sobre a situa\u00e7\u00e3o da habita\u00e7\u00e3o em Espanha e as medidas que poderiam ser tomadas para melhor\u00e1-la. Leia mais.","og_url":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/","og_site_name":"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2024-09-26T12:51:07+00:00","article_modified_time":"2024-09-26T14:36:57+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Escrito por":"Equipo Urbanitae","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"&#8220;\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel&#8221;","datePublished":"2024-09-26T12:51:07+00:00","dateModified":"2024-09-26T14:36:57+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/"},"wordCount":1423,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp","keywords":["habita\u00e7\u00e3o","setor residencial","setor residencial"],"articleSection":["Entrevistas"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/","url":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/","name":"\"\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel\" - Urbanitae Blog","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp","datePublished":"2024-09-26T12:51:07+00:00","dateModified":"2024-09-26T14:36:57+00:00","description":"Porque \u00e9 que n\u00e3o se constroem mais habita\u00e7\u00f5es em Espanha? Como aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel? Entrevistamos o CEO da Salas aqui.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/09\/manel-salas-grupo-salas.webp","width":1400,"height":735,"caption":"Manel Rodr\u00edguez, CEO del Grupo Salas. Manel Rodr\u00edguez, CEO of Grupo Salas. Manel Rodr\u00edguez, PDG de Grupo Salas. Manel Rodr\u00edguez, CEO di Grupo Salas. Manel Rodr\u00edguez, CEO do Grupo Salas. Manel Rodr\u00edguez, CEO von Grupo Salas"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2024\/09\/26\/e-necessario-aumentar-a-producao-de-habitacao-acessivel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"\u00ab\u00c9 necess\u00e1rio aumentar a produ\u00e7\u00e3o de habita\u00e7\u00e3o acess\u00edvel\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Investimento imobili\u00e1rio ao alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/pt-pt\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=50315"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/50315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media\/50340"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=50315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=50315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=50315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}