{"id":31060,"date":"2023-11-20T12:53:14","date_gmt":"2023-11-20T11:53:14","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=31060"},"modified":"2023-11-20T19:08:04","modified_gmt":"2023-11-20T18:08:04","slug":"o-mercado-imobiliario-encontra-se-num-momento-desafiador","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/","title":{"rendered":"&#8220;O mercado imobili\u00e1rio encontra-se num momento desafiador&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Com presen\u00e7a nos EUA, Canad\u00e1, \u00c1sia e Europa, a Panattoni Europe \u00e9 uma das principais promotora globais no setor imologistico. H\u00e1 tr\u00eas anos, ela est\u00e1 presente na Pen\u00ednsula Ib\u00e9rica, onde busca tornar-se uma refer\u00eancia no mercado. Conversamos sobre a empresa com Gustavo Cardozo, diretor-geral para a Panattoni Espanha e Portugal, bem como a resposta do setor ao aumento do com\u00e9rcio online. Analisamos tamb\u00e9m os desafios para manter o setor imologistico em trajet\u00f3ria de crescimento.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Panattoni consolidou-se como a maior promotora imologistica da Europa, mas chegou \u00e0 Espanha apenas h\u00e1 alguns anos. Como est\u00e1 o mercado espanhol?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O comportamento do mercado espanhol superou nossas expectativas iniciais. Felizmente, a demanda tem crescido por diversas circunst\u00e2ncias desde nossa chegada \u00e0 Pen\u00ednsula Ib\u00e9rica e, gra\u00e7as a isso, e \u00e0 confian\u00e7a depositada em n\u00f3s pela nossa matriz europeia, tanto investidores quanto clientes, conseguimos nos posicionar rapidamente entre os promotores mais ativos na regi\u00e3o. Apesar da atual incerteza econ\u00f4mica, <strong>a demanda apresenta perspectivas positivas a curto e m\u00e9dio prazo<\/strong>. Em compara\u00e7\u00e3o com os pa\u00edses ao redor, a Espanha est\u00e1 em uma posi\u00e7\u00e3o estrat\u00e9gica e possui v\u00e1rias vantagens, como seu forte poder de atra\u00e7\u00e3o de atividades industriais &#8211; especialmente no setor automotivo -, o potencial crescimento do com\u00e9rcio eletr\u00f4nico e a autonomia energ\u00e9tica do pa\u00eds, em compara\u00e7\u00e3o com outros mercados europeus. Tudo isso permite continuar atraindo mais demanda para o setor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Voc\u00eas j\u00e1 desenvolveram mais de 20 milh\u00f5es de metros quadrados de terreno log\u00edstico na Europa. Quais valores os caracterizaram como empresa nesses quase 20 anos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Temos uma vis\u00e3o internacional com foco local, ou seja, possu\u00edmos um conhecimento profundo do mercado global ao mesmo tempo em que desenvolvemos uma rede local de rela\u00e7\u00f5es. Isso nos permite n\u00e3o apenas localizar-nos em \u00e1reas estrat\u00e9gicas, mas tamb\u00e9m impactar positivamente o ambiente e as comunidades em que a <a href=\"https:\/\/panattonieurope.com\/es-es\" target=\"_blank\" rel=\"noreferrer noopener\">Panattoni<\/a> se integra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a flexibilidade. Nossa estrutura corporativa privada nos permite realizar uma governan\u00e7a e um processo decis\u00f3rio \u00e1geis e r\u00e1pidos. As decis\u00f5es locais s\u00e3o tomadas a n\u00edvel local, com o apoio da nossa matriz. Isso \u00e9 o que principalmente nos confere a agilidade e rapidez que mencionamos. Tudo isso, sempre do ponto de vista da sustentabilidade. Nosso objetivo sempre foi causar um <strong>impacto positivo a longo prazo e continuar contribuindo para o desenvolvimento de um futuro mais verde e respeitoso com o meio ambiente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A combina\u00e7\u00e3o desses tr\u00eas elementos, juntamente com uma inova\u00e7\u00e3o constante e integra\u00e7\u00e3o tecnol\u00f3gica, foi a base fundamental no desenvolvimento de nossa atividade e o que nos caracterizou ao longo dos anos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>&#8220;O aumento do com\u00e9rcio eletr\u00f4nico tem provocado um aumento nos investimentos em edif\u00edcios log\u00edsticos&#8221;<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Como o crescimento do com\u00e9rcio eletr\u00f4nico tem contribu\u00eddo nos \u00faltimos anos para o desenvolvimento do setor?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O setor do com\u00e9rcio eletr\u00f4nico tem sido um pilar fundamental para o desenvolvimento do setor. Nos \u00faltimos anos, o com\u00e9rcio eletr\u00f4nico experimentou um crescimento exponencial impulsionado por avan\u00e7os tecnol\u00f3gicos, mudan\u00e7as no comportamento do consumidor e a globaliza\u00e7\u00e3o do mercado. Essa evolu\u00e7\u00e3o transformou a din\u00e2mica do setor imobili\u00e1rio, impulsionando a demanda por espa\u00e7os log\u00edsticos e centros de distribui\u00e7\u00e3o estrategicamente localizados para atender \u00e0s necessidades de armazenamento e envio de produtos. O aumento do com\u00e9rcio eletr\u00f4nico provocou um aumento nos investimentos em edif\u00edcios log\u00edsticos, remodelando assim a forma como as propriedades imobili\u00e1rias s\u00e3o planejadas e desenvolvidas para se adaptar \u00e0s necessidades em constante mudan\u00e7a da cadeia de suprimentos e da entrega r\u00e1pida. De fato, apenas em 2022, o varejo absorveu 43% da \u00e1rea alugada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A sustentabilidade \u00e9 uma parte importante de sua proposta de valor. Os crit\u00e9rios ESG chegaram para ficar no setor imobili\u00e1rio?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Efetivamente, e o mercado demonstra isso. Nos \u00faltimos anos, houve um aumento significativo na conscientiza\u00e7\u00e3o sobre sustentabilidade e responsabilidade corporativa em todas as ind\u00fastrias, incluindo o setor imobili\u00e1rio. <strong>Investidores, inquilinos e a sociedade em geral est\u00e3o cada vez mais preocupados com o impacto ambiental e social das propriedades e projetos imobili\u00e1rios<\/strong>. Essa tend\u00eancia est\u00e1 influenciando as decis\u00f5es de investimento, o design e a constru\u00e7\u00e3o de propriedades, bem como a gest\u00e3o e opera\u00e7\u00e3o de ativos imobili\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sustentabilidade e a efici\u00eancia de toda a cadeia de suprimentos respondem a crit\u00e9rios al\u00e9m dos comerciais, tornando-se uma &#8220;necessidade&#8221; para todos que fazem parte dela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, na Panattoni, abordamos a quest\u00e3o do desenvolvimento sustent\u00e1vel de maneira abrangente, impactando positivamente nossos clientes externos e internos. Nossas decis\u00f5es sempre levam em considera\u00e7\u00e3o tr\u00eas fatores: meio ambiente, sociedade e governan\u00e7a corporativa, cada um deles importante para nossos parceiros. As diretrizes internacionais e as regulamenta\u00e7\u00f5es aplic\u00e1veis em todo o mundo para investimentos sustent\u00e1veis nos ajudaram a selecionar os <strong>Objetivos de Desenvolvimento Sustent\u00e1vel <\/strong>e a respeitar os objetivos da UE, e j\u00e1 contamos com mais de 5,7 milh\u00f5es de metros quadrados de espa\u00e7o certificado como limpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Foram anos de excelentes n\u00fameros para o setor imologistico. Como se apresentam os pr\u00f3ximos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na conjuntura atual, o cen\u00e1rio nacional experimenta certa ambiguidade e, quanto \u00e0s perspectivas futuras, h\u00e1 um senso de otimismo cauteloso. Embora as din\u00e2micas positivas possam persistir, tamb\u00e9m s\u00e3o vis\u00edveis alguns desafios, pois convergem diferentes fatores que geram uma desacelera\u00e7\u00e3o no mercado e infundem uma maior prud\u00eancia no interesse por investir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar disso, \u00e9 v\u00e1lido destacar que a <strong>necessidade de espa\u00e7o por parte dos atores log\u00edsticos<\/strong> permanece ativa, especialmente em \u00e1reas consolidadas, e espera-se que a sustentabilidade e os crit\u00e9rios ESG mantenham sua influ\u00eancia no planejamento e desenvolvimento de propriedades, refletindo uma maior conscientiza\u00e7\u00e3o ambiental e social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, \u00e9 importante considerar a poss\u00edvel volatilidade econ\u00f4mica e as mudan\u00e7as regulat\u00f3rias que podem impactar o mercado. O equil\u00edbrio entre oferta e demanda, juntamente com as condi\u00e7\u00f5es macroecon\u00f4micas, desempenhar\u00e1 um papel crucial na determina\u00e7\u00e3o da din\u00e2mica futura. Em \u00faltima an\u00e1lise, embora se antecipe um crescimento cont\u00ednuo, \u00e9 essencial enfrentar os desafios emergentes com agilidade e estrat\u00e9gias adaptativas para manter o setor imologistico em uma trajet\u00f3ria positiva nos pr\u00f3ximos anos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>&#8220;Nossas decis\u00f5es sempre levam em considera\u00e7\u00e3o tr\u00eas fatores: meio ambiente, sociedade e governan\u00e7a corporativa&#8221;<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Os ativos alternativos t\u00eam uma proje\u00e7\u00e3o muito boa no setor imobili\u00e1rio. Na verdade, voc\u00eas acabaram de formalizar a compra para desenvolver um data center na Catalunha. O investimento continuar\u00e1 crescendo nos pr\u00f3ximos anos?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O investimento se apresenta constante. Na Panattoni, nos \u00faltimos anos, apostamos na diversifica\u00e7\u00e3o tanto em mercados fora da concentra\u00e7\u00e3o do eixo Madrid-Barcelona quanto em novas estrat\u00e9gias de neg\u00f3cios e produtos imologisticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O desenvolvimento de um Data Center tem muitas semelhan\u00e7as com o de um armaz\u00e9m log\u00edstico refrigerado ou de temperatura controlada, embora, \u00e9 claro, haja algumas diferen\u00e7as not\u00e1veis. No entanto, gra\u00e7as \u00e0 nossa equipe t\u00e9cnica experiente e multidisciplinar, bem como ao apoio de consultores adequados, estamos plenamente capacitados para assumir essa responsabilidade com confian\u00e7a e garantir o sucesso, seja no campo de armazenamento de dados ou de mercadorias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Por fim, e em tra\u00e7os gerais, em que estado voc\u00eas acreditam que se encontra o mercado imobili\u00e1rio neste momento?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De forma geral, o mercado imobili\u00e1rio enfrenta um momento desafiador devido a fatores como o aumento das taxas de juros e o aumento dos custos de produ\u00e7\u00e3o. Apesar dessas situa\u00e7\u00f5es complicadas, o mercado demonstrou certa resili\u00eancia, em grande parte devido a uma demanda que se mant\u00e9m ativa. Isso nos permitiu continuar investindo e manter um alto n\u00edvel de confian\u00e7a no setor. Enquanto houver o equil\u00edbrio desejado entre oferta e demanda, algo que prevemos que continuar\u00e1 a curto prazo, n\u00e3o vemos raz\u00f5es para gerar alarme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos \u00faltimos anos, a Espanha est\u00e1 estabelecendo um ritmo de crescimento est\u00e1vel. Esperamos continuar fortalecendo nossa posi\u00e7\u00e3o no pa\u00eds e ter uma presen\u00e7a t\u00e3o relevante quanto em outros mercados nos quais a empresa est\u00e1 presente h\u00e1 mais tempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, obviamente, estamos atentos a todos os acontecimentos internacionais que est\u00e3o ocorrendo e seu potencial impacto na economia e no n\u00edvel de confian\u00e7a por parte de clientes e investidores, para que possamos nos antecipar adequadamente \u00e0s condi\u00e7\u00f5es que possam surgir no mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conhecemos a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio pelas m\u00e3os da Panattoni Europe.<\/p>\n","protected":false},"author":1,"featured_media":31061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[941],"tags":[1544],"class_list":["post-31060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas-pt","tag-panattoni-europe-5"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;O mercado imobili\u00e1rio encontra-se num momento desafiador&quot; - Urbanitae Blog<\/title>\n<meta name=\"description\" content=\"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;O mercado imobili\u00e1rio encontra-se num momento desafiador&quot; - Urbanitae Blog\" \/>\n<meta property=\"og:description\" content=\"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T11:53:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-20T18:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"&#8220;O mercado imobili\u00e1rio encontra-se num momento desafiador&#8221;\",\"datePublished\":\"2023-11-20T11:53:14+00:00\",\"dateModified\":\"2023-11-20T18:08:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/\"},\"wordCount\":1454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp\",\"keywords\":[\"Panattoni Europe\"],\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/\",\"name\":\"\\\"O mercado imobili\u00e1rio encontra-se num momento desafiador\\\" - Urbanitae Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp\",\"datePublished\":\"2023-11-20T11:53:14+00:00\",\"dateModified\":\"2023-11-20T18:08:04+00:00\",\"description\":\"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp\",\"width\":1400,\"height\":735,\"caption\":\"O mercado imobili\u00e1rio encontra-se num momento desafiador\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/2023\\\/11\\\/20\\\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;O mercado imobili\u00e1rio encontra-se num momento desafiador&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Investimento imobili\u00e1rio ao alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/pt-pt\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"O mercado imobili\u00e1rio encontra-se num momento desafiador\" - Urbanitae Blog","description":"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/","og_locale":"pt_PT","og_type":"article","og_title":"\"O mercado imobili\u00e1rio encontra-se num momento desafiador\" - Urbanitae Blog","og_description":"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.","og_url":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/","og_site_name":"Urbanitae Blog | As melhores not\u00edcias sobre investimentos imobili\u00e1rios","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2023-11-20T11:53:14+00:00","article_modified_time":"2023-11-20T18:08:04+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Escrito por":"Equipo Urbanitae","Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"&#8220;O mercado imobili\u00e1rio encontra-se num momento desafiador&#8221;","datePublished":"2023-11-20T11:53:14+00:00","dateModified":"2023-11-20T18:08:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/"},"wordCount":1454,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp","keywords":["Panattoni Europe"],"articleSection":["Entrevistas"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/","url":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/","name":"\"O mercado imobili\u00e1rio encontra-se num momento desafiador\" - Urbanitae Blog","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp","datePublished":"2023-11-20T11:53:14+00:00","dateModified":"2023-11-20T18:08:04+00:00","description":"Entrevistamos Gustavo Cardozo, diretor geral da Panattoni Espanha e Portugal, para conhecer a situa\u00e7\u00e3o atual do mercado imobili\u00e1rio.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2023\/11\/O-mercado-imobiliario-encontra-se-num-momento-desafiador.webp","width":1400,"height":735,"caption":"O mercado imobili\u00e1rio encontra-se num momento desafiador"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/2023\/11\/20\/o-mercado-imobiliario-encontra-se-num-momento-desafiador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"&#8220;O mercado imobili\u00e1rio encontra-se num momento desafiador&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#website","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Investimento imobili\u00e1rio ao alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/pt-pt\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/pt-pt\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/31060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=31060"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/posts\/31060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media\/31061"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=31060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=31060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=31060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}