{"id":88166,"date":"2025-12-12T13:51:18","date_gmt":"2025-12-12T12:51:18","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=88166"},"modified":"2026-07-02T17:51:04","modified_gmt":"2026-07-02T15:51:04","slug":"cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/","title":{"rendered":"CRE in Urbanitae: diversificazione immobiliare oltre il residenziale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Per anni, parlare di immobiliare commerciale \u2013 uffici, hotel, parchi commerciali, residenze per studenti \u2013 significava parlare di grandi operazioni. Si trattava di investimenti da diversi milioni di euro, riservati soprattutto a fondi, SOCIMI e grandi patrimoni. Questo scenario sta cambiando. Come abbiamo spiegato di recente sul blog, il CRE (<a href=\"https:\/\/mkt.urbanitae.com\/urbanitae_commercial_real_estate_it.html\" type=\"link\" id=\"https:\/\/mkt.urbanitae.com\/urbanitae_commercial_real_estate_it.html\" target=\"_blank\" rel=\"noreferrer noopener\">commercial real estate<\/a>) non \u00e8 pi\u00f9 un terreno esclusivo per i grandi investitori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Urbanitae vogliamo portare questa trasformazione un passo oltre. Il nostro obiettivo \u00e8 diventare la <strong>piattaforma integrale di investimento immobiliare<\/strong> in Europa. Cos\u00ec, quando un risparmiatore pensa di investire nel settore immobiliare \u2013 abitazioni, hotel, living alternativo o parchi commerciali, per fare qualche esempio \u2013 pu\u00f2 farlo da un unico luogo, con ticket accessibili e in un quadro regolamentato.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa intendiamo per CRE in Urbanitae<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In senso stretto, il CRE viene spesso associato a uffici e retail. Tuttavia, la realt\u00e0 del mercato \u00e8 molto pi\u00f9 ampia. In Urbanitae includiamo in questa categoria <strong>tutto ci\u00f2 che non rientra nel residenziale tradizionale<\/strong>: hotel e aparthotel, <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/01\/31\/il-boom-delle-residenze-per-studenti-domanda-redditivita-e-futuro\/\" type=\"link\" id=\"https:\/\/blog.urbanitae.com\/it\/2025\/01\/31\/il-boom-delle-residenze-per-studenti-domanda-redditivita-e-futuro\/\" target=\"_blank\" rel=\"noreferrer noopener\">residenze per studenti<\/a>, coliving e flex living, senior living, box di deposito e parcheggi, uffici, parchi commerciali e altri asset alternativi che generano redditi o attivit\u00e0 ricorrenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La logica \u00e8 semplice. In questo tipo di progetti, il valore non risiede solo nell\u2019immobile. Dipende anche dal <strong>business che quell\u2019asset \u00e8 in grado di generare<\/strong> nel tempo. Pu\u00f2 avvenire attraverso contratti di locazione, un operatore alberghiero o un acquirente istituzionale alla ricerca di un asset chiavi in mano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ad oggi, <strong>abbiamo finanziato oltre 40 operazioni CRE<\/strong>, per circa <strong>290 milioni di euro di asset under management<\/strong>. Una massa critica che rende questa linea una componente chiave della diversificazione all\u2019interno di Urbanitae.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Living gestito: residenze per studenti e coliving<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una parte rilevante della nostra attivit\u00e0 nel <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/10\/28\/investire-nel-real-estate-commerciale-non-e-piu-solo-per-i-grandi-investitori\/\" type=\"link\" id=\"https:\/\/blog.urbanitae.com\/it\/2025\/10\/28\/investire-nel-real-estate-commerciale-non-e-piu-solo-per-i-grandi-investitori\/\" target=\"_blank\" rel=\"noreferrer noopener\">CRE<\/a> riguarda il cosiddetto <strong>living gestito<\/strong>. L\u2019esempio pi\u00f9 chiaro \u00e8 <strong>Residencia Marte<\/strong>, una residenza per studenti a M\u00f3stoles, nella regione di Madrid, di fronte al campus dell\u2019Universit\u00e0 Rey Juan Carlos. Il progetto conta oltre 300 posti letto e servizi completi. \u00c8 strutturato come un\u2019operazione di plusvalenza con <strong>IRR preferenziale del 15% annuo<\/strong> per gli investitori, che hanno priorit\u00e0 nella distribuzione degli utili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Barcellona, il progetto <strong>Sants<\/strong> rappresenta il nostro ingresso nel coliving urbano. Si tratta di un asset completato, in fase di regolarizzazione, che sar\u00e0 finanziato tramite debito al 10% annuo e con una durata iniziale di 12 mesi. Il progetto prevede garanzie reali di primo grado e un rendimento minimo equivalente a nove mesi di interessi. La tesi \u00e8 chiara: forte domanda di alloggi flessibili per soggiorni brevi e medi in una delle piazze pi\u00f9 tese d\u2019Europa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrambi i progetti mostrano come il living gestito permetta all\u2019investitore retail di accedere a segmenti in cui, tradizionalmente, operavano solo fondi specializzati.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hotel e strutture turistiche: da Siviglia a Valencia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il <strong>segmento alberghiero e turistico<\/strong> \u00e8 un altro pilastro fondamentale della nostra strategia nel CRE. A Siviglia, il progetto <strong>Hotel Cruz del Campo<\/strong> si basa su un operatore di primo livello, B&amp;B Hotels, e sulla trasformazione dello storico complesso della Fabbrica Cruzcampo in uno dei nuovi assi urbani della citt\u00e0. La combinazione tra posizione strategica, rigenerazione urbana e un operatore con oltre 80 hotel in Spagna e Portogallo rende questo asset particolarmente interessante per gli acquirenti istituzionali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Valencia, il progetto <strong>San Jacinto<\/strong> consiste in un <strong>aparthotel chiavi in mano nel centro della citt\u00e0<\/strong>, finanziato tramite un prestito al 9,75% annuo. Il progetto dispone dei permessi necessari e di un acquirente finale gi\u00e0 assicurato. Questo riduce in modo significativo il rischio urbanistico e commerciale. Inoltre, offre una struttura di garanzie molto solida sull\u2019asset e sui flussi dell\u2019operazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questi due esempi illustrano bene il nostro approccio al CRE alberghiero: sviluppare o riposizionare asset per venderli successivamente a investitori istituzionali che cercano redditi stabili in location consolidate.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Retail e parchi commerciali: ricavi visibili fin dal primo giorno<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nel settore commerciale puro, ci siamo concentrati sui <strong>parchi di medie superfici e sul retail di prossimit\u00e0<\/strong>. Il progetto <strong>Navia<\/strong>, a Vigo, \u00e8 la nostra prima operazione in Galizia. Si tratta di un prestito a 15 mesi, con un interesse annuo del 10,5%, destinato a rifinanziare il terreno di un parco commerciale di medie superfici vicino alla VG-20. L\u2019operazione presenta un LTV molto prudente, pari al 25,6%, e un pacchetto di garanzie che include ipoteca di primo grado e pegno su partecipazioni, conti e ricavi futuri.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Burgos, <strong>Parque Comercial Arlanz\u00f3n<\/strong> \u00e8 uno sviluppo di quasi 9.000 m\u00b2 di superficie lorda affittabile, <strong>prelocato al 100%<\/strong> a operatori come Lupa, JYSK, Fitness Park, Popeyes o TEDi. Una volta operativo, generer\u00e0 circa 1,08 milioni di euro di reddito netto annuo. Il finanziamento \u00e8 strutturato attraverso diverse tranche di debito, con tassi intorno all\u201911% annuo e garanzie ipotecarie di primo grado sull\u2019asset.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo tipo di progetti permette all\u2019investitore di esporsi ad asset con un\u2019occupazione praticamente garantita. Inoltre, offre visibilit\u00e0 sui ricavi nel medio periodo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Box di deposito e altri tasselli del mosaico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">All\u2019interno del CRE alternativo, <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/11\/29\/oltre-il-10-di-irr-a-madrid-restituzione-del-progetto-castellanos\/\" type=\"link\" id=\"https:\/\/blog.urbanitae.com\/it\/2025\/11\/29\/oltre-il-10-di-irr-a-madrid-restituzione-del-progetto-castellanos\/\" target=\"_blank\" rel=\"noreferrer noopener\">i <strong>box di deposito<\/strong> si sono consolidati come una delle verticali con maggiore trazione in Urbanitae<\/a>. Il progetto <strong>Oporto-Franciscanos<\/strong>, sviluppato insieme a Grupanxon, finanzia la creazione di oltre 100 box di deposito tra Madrid e Albacete. L\u2019operazione si struttura tramite un prestito a 20 mesi, con interesse fisso dell\u201911% annuo e garanzie di primo grado sui locali in cui saranno ubicate le unit\u00e0. Con questo gestore abbiamo finanziato quasi venti progetti. Di questi, 14 sono gi\u00e0 stati rimborsati con ottimi risultati per gli investitori.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crescita del <em>self-storage<\/em> risponde a tendenze molto chiare: abitazioni pi\u00f9 piccole, maggiore mobilit\u00e0 lavorativa e bisogno di spazio aggiuntivo in contesti urbani densi. Per l\u2019investitore, sono asset ad alta intensit\u00e0 gestionale. Tuttavia, beneficiano di una domanda molto resiliente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Uffici prime e internazionalizzazione: il caso di Oporto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per chiudere questa panoramica sulla nostra attivit\u00e0 recente, vale la pena citare il progetto <strong>Francos<\/strong>, a Oporto. Rappresenta una tappa importante nella nostra linea dedicata agli uffici. Si tratta di un complesso con oltre <strong>20.500 m\u00b2 di uffici, coworking, aree commerciali e 180 posti auto<\/strong> nel distretto finanziario di Boavista, sviluppato insieme al gestore globale Osborne+Co. L\u2019investimento \u00e8 strutturato come un progetto di plusvalenza, con <strong>rendimento preferenziale del 15% annuo (IRR)<\/strong> per gli investitori di Urbanitae. L\u2019orizzonte di uscita stimato \u00e8 di 46-50 mesi, una volta stabilizzato l\u2019asset e venduto a un acquirente istituzionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa operazione rafforza un\u2019idea chiave: la diversificazione nel CRE non \u00e8 solo settoriale. \u00c8 anche <strong>geografica<\/strong>, con una presenza gi\u00e0 attiva in mercati come il Portogallo, oltre alla Spagna.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Verso una piattaforma realmente integrale<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il bilancio degli ultimi anni nel CRE \u00e8 chiaro: 44 operazioni, circa 290 milioni di euro di asset under management e presenza in segmenti che vanno dal living gestito ai parchi commerciali, passando per <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/06\/29\/gli-hotel-economici-conquistano-gli-investimenti-alberghieri-in-spagna\/\" type=\"link\" id=\"https:\/\/blog.urbanitae.com\/it\/2025\/06\/29\/gli-hotel-economici-conquistano-gli-investimenti-alberghieri-in-spagna\/\" target=\"_blank\" rel=\"noreferrer noopener\">hotel<\/a>, self-storage e uffici prime. Tutto questo completa la nostra attivit\u00e0 nel residenziale e nell\u2019investimento diretto. Inoltre, ci avvicina al nostro obiettivo: essere la <strong>piattaforma di riferimento quando un risparmiatore pensa di investire nel settore immobiliare<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per l\u2019investitore, la lettura \u00e8 semplice. Oggi \u00e8 gi\u00e0 possibile <strong>costruire un portafoglio immobiliare diversificato<\/strong> all\u2019interno di Urbanitae, combinando Paesi, tipologie di progetto (equity, debito) e segmenti (residenziale, CRE, alternativi). In un settore ciclico come quello immobiliare, questa diversificazione pu\u00f2 fare la differenza nella gestione del rischio di lungo periodo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Urbanitae amplia la propria offerta CRE con operazioni in hospitality, managed living, retail, self-storage e uffici prime in Spagna e Portogallo.<\/p>\n","protected":false},"author":1,"featured_media":76893,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1028],"tags":[1265,1932],"class_list":["post-88166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investimenti-immobiliari-it","tag-coliving-it","tag-investimento-immobiliare"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investimento immobiliare commerciale con Urbanitae<\/title>\n<meta name=\"description\" content=\"Scopri come l&#039;investimento immobiliare commerciale con Urbanitae permette di diversificare oltre il residenziale: hotel, retail, uffici e managed living.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CRE con Urbanitae: diversificare oltre il residenziale\" \/>\n<meta property=\"og:description\" content=\"Hotel, residenze per studenti, retail, self-storage e uffici prime: il CRE amplia la diversificazione immobiliare con Urbanitae.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-12T12:51:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-02T15:51:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"CRE in Urbanitae: diversificazione immobiliare oltre il residenziale\",\"datePublished\":\"2025-12-12T12:51:18+00:00\",\"dateModified\":\"2026-07-02T15:51:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/\"},\"wordCount\":1187,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp\",\"keywords\":[\"Coliving\",\"investimento immobiliare\"],\"articleSection\":[\"Investimenti immobiliari\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/\",\"name\":\"Investimento immobiliare commerciale con Urbanitae\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp\",\"datePublished\":\"2025-12-12T12:51:18+00:00\",\"dateModified\":\"2026-07-02T15:51:04+00:00\",\"description\":\"Scopri come l'investimento immobiliare commerciale con Urbanitae permette di diversificare oltre il residenziale: hotel, retail, uffici e managed living.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp\",\"width\":1400,\"height\":735,\"caption\":\"CRE en Urbanitae: as\u00ed hemos diversificado m\u00e1s all\u00e1 de la vivienda CRE at Urbanitae: How We\u2019ve Diversified Beyond Residential Real Estate CRE chez Urbanitae : comment nous nous sommes diversifi\u00e9s au-del\u00e0 du r\u00e9sidentiel CRE bei Urbanitae: Wie wir \u00fcber Wohnimmobilien hinaus diversifiziert haben CRE in Urbanitae: come ci siamo diversificati oltre il residenziale CRE na Urbanitae: como nos diversific\u00e1mos para al\u00e9m do residencial\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/12\\\/12\\\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CRE in Urbanitae: diversificazione immobiliare oltre il residenziale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"L'investimento immobiliare alla portata di tutti\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investimento immobiliare commerciale con Urbanitae","description":"Scopri come l'investimento immobiliare commerciale con Urbanitae permette di diversificare oltre il residenziale: hotel, retail, uffici e managed living.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/","og_locale":"it_IT","og_type":"article","og_title":"CRE con Urbanitae: diversificare oltre il residenziale","og_description":"Hotel, residenze per studenti, retail, self-storage e uffici prime: il CRE amplia la diversificazione immobiliare con Urbanitae.","og_url":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/","og_site_name":"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-12-12T12:51:18+00:00","article_modified_time":"2026-07-02T15:51:04+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Scritto da":"Equipo Urbanitae","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"CRE in Urbanitae: diversificazione immobiliare oltre il residenziale","datePublished":"2025-12-12T12:51:18+00:00","dateModified":"2026-07-02T15:51:04+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/"},"wordCount":1187,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp","keywords":["Coliving","investimento immobiliare"],"articleSection":["Investimenti immobiliari"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/","url":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/","name":"Investimento immobiliare commerciale con Urbanitae","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp","datePublished":"2025-12-12T12:51:18+00:00","dateModified":"2026-07-02T15:51:04+00:00","description":"Scopri come l'investimento immobiliare commerciale con Urbanitae permette di diversificare oltre il residenziale: hotel, retail, uffici e managed living.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/CRE-en-Urbanitae-asi-hemos-diversificado-mas-alla-de-la-vivienda.webp","width":1400,"height":735,"caption":"CRE en Urbanitae: as\u00ed hemos diversificado m\u00e1s all\u00e1 de la vivienda CRE at Urbanitae: How We\u2019ve Diversified Beyond Residential Real Estate CRE chez Urbanitae : comment nous nous sommes diversifi\u00e9s au-del\u00e0 du r\u00e9sidentiel CRE bei Urbanitae: Wie wir \u00fcber Wohnimmobilien hinaus diversifiziert haben CRE in Urbanitae: come ci siamo diversificati oltre il residenziale CRE na Urbanitae: como nos diversific\u00e1mos para al\u00e9m do residencial"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/it\/2025\/12\/12\/cre-in-urbanitae-diversificazione-immobiliare-oltre-il-residenziale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/it\/"},{"@type":"ListItem","position":2,"name":"CRE in Urbanitae: diversificazione immobiliare oltre il residenziale"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/it\/#website","url":"https:\/\/blog.urbanitae.com\/it\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"L'investimento immobiliare alla portata di tutti","publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/it\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/it\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/88166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/comments?post=88166"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/88166\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media\/76893"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media?parent=88166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/categories?post=88166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/tags?post=88166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}