{"id":79702,"date":"2026-01-23T13:47:25","date_gmt":"2026-01-23T12:47:25","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=79702"},"modified":"2026-01-23T17:08:28","modified_gmt":"2026-01-23T16:08:28","slug":"due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/","title":{"rendered":"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In Urbanitae, il rimborso di un progetto \u00e8 il momento in cui si verifica ci\u00f2 che conta davvero: che la struttura, le milestone e il monitoraggio hanno funzionato come previsto fin dall\u2019inizio. Oggi condividiamo <strong>due rimborsi<\/strong> che si sono evoluti <strong>come previsto<\/strong>, con risultati coerenti con il business plan e con tempistiche entro il perimetro comunicato agli investitori: <strong><a href=\"https:\/\/blog.urbanitae.com\/it\/2024\/10\/18\/nuovo-progetto-di-edilizia-convenzionata-a-madrid\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ribera del Pinar<\/a> e <a href=\"https:\/\/blog.urbanitae.com\/it\/2024\/07\/12\/investi-con-un-rendimento-del-105-in-12-mesi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los Fresnos<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anche se riuniamo entrambi i rimborsi in un unico articolo, si tratta di <strong>progetti indipendenti<\/strong>, con dinamiche diverse. Per questo, di seguito li analizziamo separatamente: in cosa consisteva ciascuno e com\u2019\u00e8 avvenuta la chiusura.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ribera del Pinar: edilizia convenzionata a Navalcarnero<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ribera del Pinar \u00e8 stato un progetto di debito concepito per finanziare l\u2019acquisto del terreno da parte di una cooperativa a Navalcarnero (Madrid), destinato allo sviluppo di quasi 248 abitazioni a regime protetto, nello specifico <a href=\"https:\/\/www.idealista.com\/news\/inmobiliario\/vivienda\/2022\/09\/22\/799170-que-es-la-vppl-y-cuales-son-los-requisitos-para-acceder-a-ella\" target=\"_blank\" rel=\"noreferrer noopener\">VPPL (<strong>abitazioni protette a prezzo calmierato<\/strong>)<\/a>. Il gestore era Urbanismo y Gesti\u00f3n, con una traiettoria di oltre 4.000 abitazioni consegnate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questo dettaglio \u00e8 rilevante perch\u00e9 il VPPL risponde a un\u2019esigenza particolarmente evidente nel mercato di Madrid: <strong><a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/10\/10\/la-comunita-di-madrid-lancia-un-nuovo-piano-demergenza-per-facilitare-laccesso-alla-casa\/\" target=\"_blank\" rel=\"noreferrer noopener\">case accessibili<\/a> di dimensione familiare<\/strong>. \u00c8, per cos\u00ec dire, un \u201csecondo livello\u201d all\u2019interno dell\u2019edilizia protetta: mantiene un prezzo limitato, ma consente <strong>tipologie pi\u00f9 ampie<\/strong>, pensate per nuclei che necessitano di pi\u00f9 spazio. Nell\u2019attuale contesto, segnato dalla scarsit\u00e0 di offerta di abitazioni accessibili, questo tipo di prodotto tende ad avere una domanda strutturale molto solida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel webinar, a cui hanno partecipato tutti gli attori chiave del progetto, \u00e8 stato spiegato nel dettaglio perch\u00e9, pur trattandosi di una promozione di volume significativo, <strong>la commercializzazione poteva poggiare su tre pilastri<\/strong>: domanda latente nell\u2019area di influenza, esperienza degli operatori e un prodotto con una proposta di valore chiara \u2013 qualit\u00e0, metri quadri, aree comuni e prezzo protetto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dal punto di vista <a href=\"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/glossario-dellinvestitore-immobiliare-guida-ai-termini-essenziali-per-comprendere-il-settore\/\" target=\"_blank\" rel=\"noreferrer noopener\">dell\u2019investitore<\/a>, il progetto era impostato con una durata <strong>base di 12 mesi<\/strong> e una <strong>possibile estensione di 12 mesi<\/strong>. Questa estensione non era un piano B pessimista, ma una scelta prudente: offrire margine rispetto a fattori esterni (tempi amministrativi, ritmo di adesione alla cooperativa, calendario bancario) senza forzare uno scenario di tensione se la chiusura avesse richiesto qualche settimana in pi\u00f9. Alla fine, l\u2019estensione \u00e8 stata attivata, anche se non \u00e8 stato necessario utilizzarla per intero.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Rendimento TIR dell\u201911,36%<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Durata stimata:<\/strong> 15 mesi (12 mesi pi\u00f9 una possibile estensione di altri 12)<\/li>\n\n\n\n<li><strong>Durata finale:<\/strong> 15 mesi<\/li>\n\n\n\n<li><strong>CoC stimato:<\/strong> 13,75% (aggiustato)<\/li>\n\n\n\n<li><strong>CoC finale: 13,75%<\/strong><\/li>\n\n\n\n<li><strong>TIR stimata:<\/strong> 11,50%<\/li>\n\n\n\n<li><strong>TIR finale: 11,36%<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In pratica, Ribera del Pinar si \u00e8 chiuso entro il quadro previsto, con un risultato finale coerente e senza scostamenti rilevanti rispetto alla tesi originale del progetto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los Fresnos: lotti per l\u2019autocostruzione<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/blog.urbanitae.com\/it\/2024\/07\/12\/investi-con-un-rendimento-del-105-in-12-mesi\/\" target=\"_blank\" rel=\"noreferrer noopener\">Los Fresnos<\/a> \u00e8 stato anch\u2019esso un progetto di debito, strutturato come un <strong>prestito ponte<\/strong> per agevolare l\u2019acquisizione di un terreno e i lavori necessari di <strong>frazionamento in sei lotti<\/strong>, con l\u2019obiettivo di venderli gi\u00e0 con licenza a compratori finali in regime di <strong>autopromozione (autocostruzione)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il progetto si trovava nel comparto di <strong>Los Fresnos (Boadilla del Monte)<\/strong>, una zona consolidata di ville unifamiliari di alto livello, con buona accessibilit\u00e0 e servizi nelle vicinanze. La strategia si basava su un\u2019idea semplice: nei mercati in cui esiste domanda da parte di autopromotori e il prodotto viene offerto \u201cchiavi in mano\u201d (lotto con licenza, contratto di promozione delegata e costruzione a prezzo fisso), la tempistica pu\u00f2 ridursi significativamente rispetto a una promozione tradizionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questo caso, inoltre, il progetto aveva un promotore, Auric Partners, con esperienza in operazioni di questo tipo e con una conoscenza specifica del mercato locale, ed era impostato con <strong>una durata complessiva di 12 mesi<\/strong>, con <strong>una possibile estensione di 6 mesi<\/strong> per coprire eventuali scostamenti ragionevoli nei tempi di rilascio delle licenze o nella chiusura commerciale dei lotti.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Rendimento TIR del 10,21%<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Durata stimata:<\/strong> 18 mesi (12 + 6 di estensione)<\/li>\n\n\n\n<li><strong>Durata finale: 18 mesi<\/strong><\/li>\n\n\n\n<li><strong>CoC stimato:<\/strong> 15,75% (aggiustato)<\/li>\n\n\n\n<li><strong>CoC finale: 15,75%<\/strong><\/li>\n\n\n\n<li><strong>TIR stimata:<\/strong> 10,50%<\/li>\n\n\n\n<li><strong>TIR finale: 10,21%<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Il rimborso di Los Fresnos ha evidenziato l\u2019importanza di conoscere bene il mercato locale, lavorare con promotori specializzati nella tipologia di asset e strutturare operazioni con garanzie e ratio conservativi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un\u2019esecuzione allineata alle previsioni<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nel complesso, i rimborsi di <strong><a href=\"https:\/\/blog.urbanitae.com\/it\/2024\/10\/18\/nuovo-progetto-di-edilizia-convenzionata-a-madrid\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ribera del Pinar<\/a> e Los Fresnos<\/strong> riflettono un\u2019esecuzione allineata alle ipotesi definite fin dall\u2019inizio. In entrambi i casi, i progetti si sono sviluppati entro tempistiche ragionevoli, con risultati finali pari o superiori alle previsioni e senza criticit\u00e0 rilevanti nel rimborso del capitale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Due esempi diversi \u2013 <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/07\/31\/la-crescita-delledilizia-residenziale-agevolata-e-sufficiente-per-colmare-il-deficit\/\" target=\"_blank\" rel=\"noreferrer noopener\">edilizia protetta<\/a> su larga scala e sviluppo residenziale di dimensioni pi\u00f9 contenute \u2013 che mostrano come una corretta strutturazione, una domanda verificata e promotori con esperienza possano offrire visibilit\u00e0 e stabilit\u00e0 agli investitori anche in contesti di mercato sfidanti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due rimborsi, due strategie: VPPL a Navalcarnero e lotti con licenza a Boadilla. Ecco cosa finanziava ogni progetto e perch\u00e9 la chiusura \u00e8 rimasta in linea.<\/p>\n","protected":false},"author":1,"featured_media":79712,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[928,1084],"tags":[],"class_list":["post-79702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-progetti","category-urbanitae-it"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo<\/title>\n<meta name=\"description\" content=\"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ribera del Pinar e Los Fresnos: due rimborsi come previsto\" \/>\n<meta property=\"og:description\" content=\"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-23T12:47:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T16:08:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo\",\"datePublished\":\"2026-01-23T12:47:25+00:00\",\"dateModified\":\"2026-01-23T16:08:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/\"},\"wordCount\":764,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Destacada-blog-79.webp\",\"articleSection\":[\"Progetti\",\"Urbanitae\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/\",\"name\":\"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Destacada-blog-79.webp\",\"datePublished\":\"2026-01-23T12:47:25+00:00\",\"dateModified\":\"2026-01-23T16:08:28+00:00\",\"description\":\"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Destacada-blog-79.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Destacada-blog-79.webp\",\"width\":1400,\"height\":735,\"caption\":\"Dos devoluciones seg\u00fan lo previsto: Ribera del Pinar y Los Fresnos cierran su ciclo. Two repayments delivered as planned: Ribera del Pinar and Los Fresnos close their cycle. Deux remboursements comme pr\u00e9vu : Ribera del Pinar et Los Fresnos bouclent leur cycle. Zwei R\u00fcckzahlungen wie geplant: Ribera del Pinar und Los Fresnos schlie\u00dfen ihren Zyklus ab. Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo. Dois reembolsos como previsto: Ribera del Pinar e Los Fresnos fecham o seu ciclo.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2026\\\/01\\\/23\\\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"L'investimento immobiliare alla portata di tutti\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo","description":"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/","og_locale":"it_IT","og_type":"article","og_title":"Ribera del Pinar e Los Fresnos: due rimborsi come previsto","og_description":"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.","og_url":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/","og_site_name":"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2026-01-23T12:47:25+00:00","article_modified_time":"2026-01-23T16:08:28+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Scritto da":"Equipo Urbanitae","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo","datePublished":"2026-01-23T12:47:25+00:00","dateModified":"2026-01-23T16:08:28+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/"},"wordCount":764,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp","articleSection":["Progetti","Urbanitae"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/","url":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/","name":"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp","datePublished":"2026-01-23T12:47:25+00:00","dateModified":"2026-01-23T16:08:28+00:00","description":"Ribera del Pinar e Los Fresnos: due rimborsi come previsto, tempi rispettati e TIR dell\u201911,36% e del 10,21%.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/01\/Destacada-blog-79.webp","width":1400,"height":735,"caption":"Dos devoluciones seg\u00fan lo previsto: Ribera del Pinar y Los Fresnos cierran su ciclo. Two repayments delivered as planned: Ribera del Pinar and Los Fresnos close their cycle. Deux remboursements comme pr\u00e9vu : Ribera del Pinar et Los Fresnos bouclent leur cycle. Zwei R\u00fcckzahlungen wie geplant: Ribera del Pinar und Los Fresnos schlie\u00dfen ihren Zyklus ab. Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo. Dois reembolsos como previsto: Ribera del Pinar e Los Fresnos fecham o seu ciclo."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/it\/2026\/01\/23\/due-rimborsi-come-previsto-ribera-del-pinar-e-los-fresnos-chiudono-il-loro-ciclo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/it\/"},{"@type":"ListItem","position":2,"name":"Due rimborsi come previsto: Ribera del Pinar e Los Fresnos chiudono il loro ciclo"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/it\/#website","url":"https:\/\/blog.urbanitae.com\/it\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"L'investimento immobiliare alla portata di tutti","publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/it\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/it\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/79702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/comments?post=79702"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/79702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media\/79712"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media?parent=79702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/categories?post=79702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/tags?post=79702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}