{"id":62869,"date":"2025-04-29T13:50:45","date_gmt":"2025-04-29T11:50:45","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=62869"},"modified":"2025-04-29T16:47:53","modified_gmt":"2025-04-29T14:47:53","slug":"navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/","title":{"rendered":"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">In Urbanitae insistiamo sempre sul fatto che ogni investimento comporta dei rischi e che, sebbene facciamo tutto il possibile per minimizzare gli imprevisti, non possiamo garantire una redditivit\u00e0 specifica. Il caso del progetto <a href=\"https:\/\/urbanitae.com\/it\/progetto\/P000139\" target=\"_blank\" rel=\"noreferrer noopener\">Navas de Tolosa<\/a>, a Barcellona, la cui liquidazione si \u00e8 recentemente conclusa, illustra bene questa realt\u00e0 e dimostra anche come, con una gestione proattiva e orientata alla tutela degli interessi degli investitori, sia possibile ottenere risultati positivi anche in contesti difficili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il progetto, finanziato nel dicembre 2021, consisteva nello sviluppo di un edificio con 15 abitazioni, un locale commerciale e 16 posti auto. Inizialmente previsto con una durata di 22 mesi e una redditivit\u00e0 stimata del 29,9% (con un TIR del 15,3%), il progetto si \u00e8 chiuso infine con un ritorno lordo del 16,2% e un TIR del 4,7% dopo 39 mesi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa \u00e8 successo?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lo sviluppo del progetto \u00e8 stato influenzato da una serie di circostanze difficili da prevedere al momento del finanziamento:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Aumento dei costi di costruzione:<\/strong> L\u2019appalto dei lavori \u00e8 avvenuto in un periodo di forte aumento dei prezzi e scarsit\u00e0 di materiali nel 2022. Il costo finale di costruzione \u00e8 stato superiore del 23% rispetto alla stima iniziale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Urgenza nell\u2019avvio dei lavori:<\/strong> Per evitare che la licenza edilizia scadesse \u2013 il che avrebbe imposto di destinare il 30% dell\u2019edificio a edilizia residenziale pubblica \u2013 \u00e8 stato necessario avviare rapidamente i lavori, dando priorit\u00e0 ad alcune fasi come il movimento terra e le fondamenta. Questo ha ridotto il margine di negoziazione con fornitori e imprese edili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Contesto economico sfavorevole:<\/strong> Durante la fase di commercializzazione, l\u2019aumento dei tassi di interesse e l\u2019incertezza normativa (soprattutto intorno al golden visa) hanno rallentato le vendite. Al termine dei lavori, oltre la met\u00e0 degli appartamenti non era ancora stata venduta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Costi finanziari e di vendita pi\u00f9 alti:<\/strong> A causa della congiuntura economica, il costo del prestito per lo sviluppo \u00e8 salito al 5,5% di interesse rispetto al 2,5% previsto. Inoltre, \u00e8 stato necessario rafforzare le attivit\u00e0 di marketing e aumentare le commissioni degli agenti immobiliari per velocizzare le vendite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cosa ha fatto Urbanitae<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nonostante queste difficolt\u00e0, Urbanitae ha lavorato fianco a fianco con il promotore per trovare soluzioni volte a ridurre l\u2019impatto:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Ottimizzazione del progetto:<\/strong> Sono stati eliminati alcuni oneri, come l\u2019obbligo di destinare uno spazio a una cabina elettrica, convertendolo in superficie abitabile, il che ha permesso di aumentare i ricavi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Flessibilit\u00e0 nella commercializzazione:<\/strong> Sono state adattate le strategie di vendita, arredando alcune unit\u00e0 e collaborando con nuove agenzie immobiliari.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2013 Acquisto delle unit\u00e0 residue:<\/strong> Per chiudere l\u2019operazione, il promotore ha acquistato i tre posti auto rimanenti al prezzo pubblicato, evitando una vendita a sconto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie a queste misure, anche se la redditivit\u00e0 non ha raggiunto le previsioni iniziali, il progetto <strong>si \u00e8 chiuso con un ritorno positivo del 16,2% per gli investitori.<\/strong> Non si sono registrate perdite di capitale e l\u2019investimento \u00e8 stato protetto in un contesto molto complesso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una lezione su rischio e investimento immobiliare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il progetto <a href=\"https:\/\/urbanitae.com\/it\/progetto\/P000139\">Navas de Tolosa<\/a> evidenzia uno degli aspetti fondamentali dell\u2019investimento immobiliare: <strong>la redditivit\u00e0 non \u00e8 garantita.<\/strong> Come in ogni tipo di investimento, esistono rischi che possono incidere sia sui tempi sia sui profitti. Tuttavia, dimostra anche che, a differenza dei mercati finanziari, <a href=\"https:\/\/blog.urbanitae.com\/it\/2025\/04\/13\/perche-linvestimento-immobiliare-resiste-alla-volatilita-dei-mercati\/\" target=\"_blank\" rel=\"noreferrer noopener\">il mattone \u00e8 molto pi\u00f9 resiliente<\/a>. E infine conferma che una gestione professionale e attiva pu\u00f2 fare la differenza, <strong>aiutando a preservare il capitale e ottenere risultati positivi<\/strong> anche in scenari avversi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da parte nostra, in <a href=\"https:\/\/urbanitae.com\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Urbanitae<\/a> restiamo impegnati a offrire agli investitori la massima trasparenza, spiegando chiaramente sia le opportunit\u00e0 sia i rischi di ogni progetto. Il nostro obiettivo \u00e8 continuare a costruire <strong>un rapporto di fiducia a lungo termine<\/strong>, basato su informazioni chiare, una selezione prudente dei progetti e una gestione attiva orientata alla tutela degli interessi di chi si affida a noi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto Navas de Tolosa, a Barcellona, si \u00e8 concluso con un rendimento totale del 16% in 39 mesi per gli investitori di Urbanitae, con un TIR del 4,7%. <\/p>\n","protected":false},"author":1,"featured_media":62852,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1058,928],"tags":[1960,1932,1933,1011],"class_list":["post-62869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-equity-it","category-progetti","tag-equity-crowdfunding-it","tag-investimento-immobiliare","tag-rendimento","tag-urbanitae-it"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti<\/title>\n<meta name=\"description\" content=\"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spieghiamo i risultati del progetto Navas de Tolosa\" \/>\n<meta property=\"og:description\" content=\"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T11:50:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T14:47:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti\",\"datePublished\":\"2025-04-29T11:50:45+00:00\",\"dateModified\":\"2025-04-29T14:47:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"keywords\":[\"equity crowdfunding\",\"investimento immobiliare\",\"rendimento\",\"Urbanitae\"],\"articleSection\":[\"Equity\",\"Progetti\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/\",\"name\":\"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"datePublished\":\"2025-04-29T11:50:45+00:00\",\"dateModified\":\"2025-04-29T14:47:53+00:00\",\"description\":\"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/navas-de-tolosa-rentabilidad.webp\",\"width\":1400,\"height\":735,\"caption\":\"Navas de Tolosa: rentabilidad positiva pese a los imprevistos. Navas de Tolosa: Positive returns despite unforeseen events. Navas de Tolosa : Rentabilit\u00e9 positive malgr\u00e9 les impr\u00e9vus. Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti. Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos. Navas de Tolosa: Positive Rendite trotz unvorhergesehener Ereignisse.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/2025\\\/04\\\/29\\\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"L'investimento immobiliare alla portata di tutti\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/it\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti","description":"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/","og_locale":"it_IT","og_type":"article","og_title":"Spieghiamo i risultati del progetto Navas de Tolosa","og_description":"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.","og_url":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/","og_site_name":"Urbanitae Blog | Le migliori notizie sugli investimenti immobiliari","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-04-29T11:50:45+00:00","article_modified_time":"2025-04-29T14:47:53+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Scritto da":"Equipo Urbanitae","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti","datePublished":"2025-04-29T11:50:45+00:00","dateModified":"2025-04-29T14:47:53+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","keywords":["equity crowdfunding","investimento immobiliare","rendimento","Urbanitae"],"articleSection":["Equity","Progetti"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/","url":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/","name":"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","datePublished":"2025-04-29T11:50:45+00:00","dateModified":"2025-04-29T14:47:53+00:00","description":"Spieghiamo perch\u00e9 la redditivit\u00e0 del progetto Navas de Tolosa non \u00e8 stata quella attesa e cosa abbiamo fatto per preservare il capitale degli investitori.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/04\/navas-de-tolosa-rentabilidad.webp","width":1400,"height":735,"caption":"Navas de Tolosa: rentabilidad positiva pese a los imprevistos. Navas de Tolosa: Positive returns despite unforeseen events. Navas de Tolosa : Rentabilit\u00e9 positive malgr\u00e9 les impr\u00e9vus. Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti. Navas de Tolosa: Rentabilidade positiva apesar dos imprevistos. Navas de Tolosa: Positive Rendite trotz unvorhergesehener Ereignisse."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/it\/2025\/04\/29\/navas-de-tolosa-redditivita-positiva-nonostante-gli-imprevisti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/it\/"},{"@type":"ListItem","position":2,"name":"Navas de Tolosa: Redditivit\u00e0 positiva nonostante gli imprevisti"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/it\/#website","url":"https:\/\/blog.urbanitae.com\/it\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"L'investimento immobiliare alla portata di tutti","publisher":{"@id":"https:\/\/blog.urbanitae.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/it\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/it\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/it\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/62869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/comments?post=62869"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/posts\/62869\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media\/62852"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/media?parent=62869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/categories?post=62869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/it\/wp-json\/wp\/v2\/tags?post=62869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}