{"id":89212,"date":"2026-07-23T09:43:43","date_gmt":"2026-07-23T07:43:43","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=89212"},"modified":"2026-07-23T09:45:34","modified_gmt":"2026-07-23T07:45:34","slug":"mirador-sur-plus-value-pour-240-logements-a-albal-valence","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/","title":{"rendered":"Mirador Sur : plus-value pour 240 logements \u00e0 Albal, Valence"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"89212\" class=\"elementor elementor-89212 elementor-89196\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-213e33eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"213e33eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d8c782\" data-id=\"7d8c782\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5968fc16 elementor-widget elementor-widget-text-editor\" data-id=\"5968fc16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>Le prochain <strong>lundi 27 juillet \u00e0 16 h 00 (UTC+2)<\/strong>, nous ouvrirons \u00e0 l\u2019investissement <strong>le projet Mirador Sur<\/strong>, une nouvelle opportunit\u00e9 de plus-value \u00e0 Albal, Valence.<\/p>\n<p> <\/p>\n<p>L\u2019op\u00e9ration consiste \u00e0 participer, aux c\u00f4t\u00e9s du promoteur, au d\u00e9veloppement d\u2019une promotion de <strong>240 logements collectifs<\/strong>, r\u00e9partis dans <strong>3 tours<\/strong>, avec des typologies de 1 \u00e0 3 chambres.<\/p>\n<p> <\/p>\n<p>Le projet offre aux investisseurs d\u2019Urbanitae un <strong>TRI pr\u00e9f\u00e9rentiel de 21,15 %<\/strong> et pr\u00e9sente une dur\u00e9e estim\u00e9e de <strong>48-54 mois<\/strong>.<\/p>\n<p> <\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Ouverture \u00e0 l\u2019investissement :<\/strong> lundi 27 juillet \u00e0 16 h 00 (UTC+2)<\/li>\n \n<li><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_jnUiLlFjQLeSKgvYl1UDJQ\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Webinaire<\/strong><\/a> <strong>du projet :<\/strong> jeudi 23 juillet \u00e0 12 h 00 (UTC+2)<\/li>\n<\/ul>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">240 logements dans 3 tours<\/h2>\n<p> <\/p>\n<p><a href=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_1&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_1&amp;utm_content=fr_proyecto_mirador_sur\">Mirador Sur<\/a> pr\u00e9voit le d\u00e9veloppement de <strong>240 logements collectifs<\/strong> dans la commune d\u2019Albal, au sein de l\u2019aire m\u00e9tropolitaine sud de Valence.<\/p>\n<p> <\/p>\n<p>La promotion sera organis\u00e9e en <strong>3 tours ind\u00e9pendantes<\/strong>, une configuration qui permet de maximiser l\u2019entr\u00e9e de lumi\u00e8re naturelle et d\u2019optimiser les typologies. Tous les logements seront ext\u00e9rieurs et disposeront de distributions de 1, 2 et 3 chambres.<\/p>\n<p> <\/p>\n<p>L\u2019op\u00e9ration pr\u00e9voit de financer les co\u00fbts de d\u00e9marrage du d\u00e9veloppement, ainsi que l\u2019annulation de la dette qui gr\u00e8ve actuellement le terrain, correspondant \u00e0 un pr\u00eat relais d\u2019Urbanitae.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Un emplacement m\u00e9tropolitain \u00e0 c\u00f4t\u00e9 de Valence<\/h2>\n<p> <\/p>\n<p>Le terrain est situ\u00e9 \u00e0 Albal, dans la comarque de l\u2019Horta Sud, \u00e0 moins de <strong>10 kilom\u00e8tres du centre de Valence<\/strong>.<\/p>\n<p> <\/p>\n<p>La commune dispose de connexions directes via la V-31 et l\u2019A-7, deux des principaux axes routiers de l\u2019aire m\u00e9tropolitaine. En outre, une nouvelle gare Renfe est en cours de d\u00e9veloppement \u00e0 environ <strong>400 m\u00e8tres du projet<\/strong>. Elle reliera Albal au centre de Valence en moins de 15 minutes.<\/p>\n<p> <\/p>\n<p>Albal fait partie d\u2019une aire m\u00e9tropolitaine qui d\u00e9passe les <strong>129 000 habitants<\/strong>, avec des communes voisines telles que Catarroja, Silla et Alfafar. Il s\u2019agit d\u2019une zone r\u00e9sidentielle consolid\u00e9e, avec acc\u00e8s \u00e0 des \u00e9tablissements \u00e9ducatifs, des installations sportives, des commerces et des espaces verts.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Le gestionnaire : ConfortHogar<\/h2>\n<p> <\/p>\n<p>Le gestionnaire du projet est une soci\u00e9t\u00e9 du groupe ConfortHogar, promoteur local exp\u00e9riment\u00e9 dans le d\u00e9veloppement de logements neufs dans la Communaut\u00e9 valencienne.<\/p>\n<p> <\/p>\n<p><a href=\"https:\/\/blog.urbanitae.com\/fr\/2025\/05\/16\/vedat-ehomes-rentabilite-de-366-a-torrent-valence\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=urbanitae_collabore&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/blog.urbanitae.com\/fr\/2025\/05\/16\/vedat-ehomes-rentabilite-de-366-a-torrent-valence\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=urbanitae_collabore&amp;utm_content=fr_proyecto_mirador_sur\">Urbanitae a d\u00e9j\u00e0 collabor\u00e9 avec ce gestionnaire sur d\u2019autres projets<\/a>, ce qui permet de disposer d\u2019une connaissance pr\u00e9alable de sa mani\u00e8re de travailler et de sa capacit\u00e9 d\u2019ex\u00e9cution.<\/p>\n<p> <\/p>\n<p>Dans Mirador Sur, le promoteur investira ses fonds propres et ceux de ses associ\u00e9s aux c\u00f4t\u00e9s du capital des investisseurs d\u2019Urbanitae et d\u2019autres investisseurs additionnels. Cela renforce l\u2019alignement des int\u00e9r\u00eats entre les parties.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">TRI pr\u00e9f\u00e9rentiel de 21,15 %<\/h2>\n<p> <\/p>\n<p><a href=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_2&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_2&amp;utm_content=fr_proyecto_mirador_sur\">Mirador Sur<\/a> est structur\u00e9 comme un projet de plus-value. Les apports des investisseurs d\u2019Urbanitae seront canalis\u00e9s par une augmentation de capital dans une <a href=\"https:\/\/blog.urbanitae.com\/fr\/glossaire\/spv-special-purpose-vehicle\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=societe_vehicule&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/blog.urbanitae.com\/fr\/glossaire\/spv-special-purpose-vehicle\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=societe_vehicule&amp;utm_content=fr_proyecto_mirador_sur\">soci\u00e9t\u00e9 v\u00e9hicule<\/a> cr\u00e9\u00e9e pour l\u2019op\u00e9ration, qui entrera ensuite dans la soci\u00e9t\u00e9 promotrice du projet.<\/p>\n<p> <\/p>\n<p>Les principales caract\u00e9ristiques de l\u2019op\u00e9ration sont les suivantes :<\/p>\n<p> <\/p>\n<ul class=\"wp-block-list\">\n<li><strong>Type de projet :<\/strong> plus-value<\/li>\n \n<li><strong>Localisation :<\/strong> Albal, Valence<\/li>\n \n<li><strong>Produit :<\/strong> 240 logements dans 3 tours<\/li>\n \n<li><strong>Ticket Urbanitae :<\/strong> 2 000 000 euros<\/li>\n \n<li><strong>Dur\u00e9e estim\u00e9e :<\/strong> 48-54 mois<\/li>\n \n<li><strong>TRI pr\u00e9f\u00e9rentiel :<\/strong> 21,15 %<\/li>\n<\/ul>\n<p> <\/p>\n<p>La structure de distribution \u00e9tablit que les investisseurs d\u2019Urbanitae de cette premi\u00e8re tranche auront une priorit\u00e9 de paiement jusqu\u2019\u00e0 r\u00e9cup\u00e9rer leur investissement, plus un <a href=\"https:\/\/blog.urbanitae.com\/fr\/2025\/05\/30\/que-sont-les-projets-avec-tri-preferentiel-chez-urbanitae\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=tri_preferentiel&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/blog.urbanitae.com\/fr\/2025\/05\/30\/que-sont-les-projets-avec-tri-preferentiel-chez-urbanitae\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=tri_preferentiel&amp;utm_content=fr_proyecto_mirador_sur\"><strong>TRI pr\u00e9f\u00e9rentiel<\/strong><\/a> <strong>de 21,15 %<\/strong>.<\/p>\n<p> <\/p>\n<p>Les investisseurs de la deuxi\u00e8me tranche, pr\u00e9vue lors de l\u2019obtention du permis de construire, b\u00e9n\u00e9ficieront pour leur part d\u2019un rendement pr\u00e9f\u00e9rentiel de <strong>17,29 % de TRI<\/strong>. Ce n\u2019est qu\u2019apr\u00e8s avoir satisfait ces rendements pr\u00e9f\u00e9rentiels que le promoteur r\u00e9cup\u00e9rera son capital et une rentabilit\u00e9 \u00e9quivalente.<\/p>\n<p> <\/p>\n<p>Si des <a href=\"https:\/\/blog.urbanitae.com\/fr\/2026\/01\/30\/waterfalls-dans-les-projets-dequity-pourquoi-la-repartition-des-benefices-compte-beaucoup\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=benefices_supplementaires&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/blog.urbanitae.com\/fr\/2026\/01\/30\/waterfalls-dans-les-projets-dequity-pourquoi-la-repartition-des-benefices-compte-beaucoup\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=benefices_supplementaires&amp;utm_content=fr_proyecto_mirador_sur\">b\u00e9n\u00e9fices suppl\u00e9mentaires<\/a> sont g\u00e9n\u00e9r\u00e9s au-del\u00e0 de ce seuil, le promoteur recevra <strong>50 % de l\u2019exc\u00e9dent<\/strong>, <strong>5 %<\/strong> seront destin\u00e9s \u00e0 la structuration du capital, et le reste sera distribu\u00e9 en fonction du pourcentage de capital d\u00e9tenu par chaque partie.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Permis, financement et commercialisation<\/h2>\n<p> <\/p>\n<p>Le permis de construire sera demand\u00e9 dans les prochains mois. Son obtention n\u00e9cessite au pr\u00e9alable l\u2019approbation de la modification ponctuelle du Plan g\u00e9n\u00e9ral d\u2019Albal. Il est estim\u00e9 qu\u2019il pourra \u00eatre obtenu dans un d\u00e9lai approximatif de <strong>18 mois<\/strong>.<\/p>\n<p> <\/p>\n<p>Sur le plan financier, le projet disposera d\u2019un financement senior bancaire d\u2019un montant approximatif de <strong>35 millions d\u2019euros<\/strong>, incluant les montants vers\u00e9s \u00e0 compte par les clients. Ce financement est actuellement en n\u00e9gociation avec deux \u00e9tablissements.<\/p>\n<p> <\/p>\n<p>La commercialisation est pr\u00e9vue pour <strong>octobre 2026<\/strong>, avec un rythme de vente estim\u00e9 \u00e0 8 unit\u00e9s par mois pendant 30 mois, jusqu\u2019\u00e0 compl\u00e9ter les 240 logements.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5774c8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5774c8c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ff58fd\" data-id=\"2ff58fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d93c87d elementor-widget elementor-widget-video\" data-id=\"d93c87d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/XaI1E-CzUww&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5795232 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5795232\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-757d83a\" data-id=\"757d83a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b0c69 elementor-widget elementor-widget-text-editor\" data-id=\"77b0c69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"wp-block-heading\">Pourquoi investir dans le projet Mirador Sur<\/h2><p>Voici quelques-uns des principaux points forts de l\u2019<a href=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=operation&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=operation&amp;utm_content=fr_proyecto_mirador_sur\">op\u00e9ration<\/a> :<\/p><ul class=\"wp-block-list\"><li><strong>Promotion de 240 logements<\/strong> dans l\u2019aire m\u00e9tropolitaine sud de Valence.<\/li><li><strong>Emplacement \u00e0 Albal<\/strong>, \u00e0 moins de 10 kilom\u00e8tres du centre de la capitale.<\/li><li><strong>Nouvelle gare Renfe pr\u00e9vue \u00e0 400 m\u00e8tres<\/strong> du projet.<\/li><li><strong>Produit comp\u00e9titif<\/strong>, avec 3 tours ind\u00e9pendantes et des logements 100 % ext\u00e9rieurs.<\/li><li><strong>TRI pr\u00e9f\u00e9rentiel de 21,15 %<\/strong> pour les investisseurs d\u2019Urbanitae de cette premi\u00e8re tranche.<\/li><li><strong>Financement senior bancaire pr\u00e9vu<\/strong> pour environ 35 millions d\u2019euros.<\/li><li><strong>Promoteur local exp\u00e9riment\u00e9<\/strong> dans le logement neuf dans la Communaut\u00e9 valencienne.<\/li><li><strong>Apport en capital du promoteur<\/strong>, aux c\u00f4t\u00e9s du capital d\u2019Urbanitae et d\u2019autres investisseurs.<\/li><\/ul><h2 class=\"wp-block-heading\">Quelle rentabilit\u00e9 puis-je obtenir ?<\/h2><p>Dans les projets d\u2019equity, la r\u00e9glementation applicable ne permet pas aux plateformes de financement participatif de communiquer une rentabilit\u00e9 estim\u00e9e pr\u00e9cise du projet. C\u2019est pourquoi Urbanitae publie, sur la page de chaque opportunit\u00e9, trois sc\u00e9narios \u00e9conomiques \u2013 favorable, mod\u00e9r\u00e9 et d\u00e9favorable \u2013 avec diff\u00e9rentes hypoth\u00e8ses de revenus et de co\u00fbts.<\/p><p>Dans tous les cas, la formule de calcul est la m\u00eame : <strong>pr\u00e9vision des revenus moins estimation des co\u00fbts, divis\u00e9e par l\u2019equity total<\/strong>.<\/p><p>Dans le sc\u00e9nario favorable de Mirador Sur, la pr\u00e9vision totale des revenus s\u2019\u00e9l\u00e8ve \u00e0 <strong>55 826 416 euros<\/strong>, tandis que l\u2019estimation des co\u00fbts totaux correspond \u00e0 <strong>47 285 862 euros<\/strong>, sur un equity total de <strong>8 300 000 euros<\/strong>.<\/p><p>Ces pr\u00e9visions sont des estimations et peuvent varier en fonction de l\u2019\u00e9volution \u00e9conomique, commerciale, technique ou de toute autre circonstance pendant la dur\u00e9e de vie du projet.<\/p><h2 class=\"wp-block-heading\">Calendrier estim\u00e9<\/h2><p>La dur\u00e9e estim\u00e9e du projet est de <strong>48-54 mois<\/strong>.<\/p><p>Les principaux jalons pr\u00e9vus sont les suivants :<\/p><ul class=\"wp-block-list\"><li><strong>Troisi\u00e8me trimestre 2026 :<\/strong> augmentation de capital et d\u00e9marches administratives.<\/li><li><strong>Quatri\u00e8me trimestre 2026 :<\/strong> d\u00e9but de la commercialisation.<\/li><li><strong>Quatri\u00e8me trimestre 2027 :<\/strong> obtention du permis de construire et augmentation de capital de la deuxi\u00e8me tranche.<\/li><li><strong>Premier trimestre 2030 :<\/strong> ach\u00e8vement pr\u00e9vu de la construction.<\/li><li><strong>Quatri\u00e8me trimestre 2030 :<\/strong> livraison des logements, liquidation de la soci\u00e9t\u00e9 et distribution des b\u00e9n\u00e9fices aux investisseurs.<\/li><\/ul><p>Comme dans toute promotion immobili\u00e8re, les d\u00e9lais peuvent varier \u00e0 la hausse comme \u00e0 la baisse en fonction de l\u2019\u00e9volution r\u00e9elle du projet, des d\u00e9marches administratives, des travaux, de la commercialisation et des conditions de financement.<\/p><h2 class=\"wp-block-heading\">Vous avez des questions sur le projet ?<\/h2><p>L\u2019ouverture \u00e0 l\u2019investissement de <a href=\"https:\/\/urbanitae.com\/fr\/projet\/P000501\/?utm_source=blog_fr&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_3&amp;utm_content=fr_proyecto_mirador_sur\" target=\"_blank\" rel=\"noreferrer noopener\" data-type=\"link\" data-id=\"https:\/\/urbanitae.com\/en\/project\/P000501\/?utm_source=blog_en&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0726&amp;utm_term=mirador_sur_3&amp;utm_content=en_proyecto_mirador_sur\"><strong>Mirador Sur<\/strong><\/a> aura lieu le <strong>lundi 27 juillet \u00e0 16 h 00 (UTC+2)<\/strong>.<\/p><p>Vous pouvez poser vos questions lors du <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_jnUiLlFjQLeSKgvYl1UDJQ\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>webinaire<\/strong><\/a> <strong>du jeudi 23 juillet \u00e0 12 h 00 (UTC+2)<\/strong>.<\/p><p>Vous pouvez \u00e9galement nous \u00e9crire \u00e0 <a href=\"mailto:contacto@urbanitae.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>contacto@urbanitae.com<\/strong><\/a> ou nous appeler au <strong>(+34) 911 23 25 22<\/strong>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mirador Sur permet de participer \u00e0 un programme de 240 logements \u00e0 Albal, dans l&#8217;aire m\u00e9tropolitaine de Valence, avec un TRI pr\u00e9f\u00e9rentiel de 21,15 % et un financement bancaire pr\u00e9vu.<\/p>\n","protected":false},"author":1,"featured_media":89211,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1057,927],"tags":[1176,1964,1958,1887,1937],"class_list":["post-89212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projets-fr","category-projets","tag-comunidad-valenciana-fr","tag-crowdfunding-immobilier","tag-financement-participatif-capital","tag-investissement-immobilier-2","tag-secteur-residentiel"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investir dans le logement \u00e0 Valence : Mirador Sur<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment investir dans le logement \u00e0 Valence avec Mirador Sur : 240 logements \u00e0 Albal, TRI pr\u00e9f\u00e9rentiel de 21,15 % et financement bancaire pr\u00e9vu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mirador Sur : 240 logements dans l&#039;aire m\u00e9tropolitaine de Valence\" \/>\n<meta property=\"og:description\" content=\"Nouvelle opportunit\u00e9 de plus-value \u00e0 Albal, \u00e0 moins de 10 kilom\u00e8tres de Valence, avec 240 logements r\u00e9partis dans trois tours et un TRI pr\u00e9f\u00e9rentiel pour les investisseurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Les meilleures nouvelles sur l&#039;investissement immobilier\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-23T07:43:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-23T07:45:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Mirador Sur : plus-value pour 240 logements \u00e0 Albal, Valence\",\"datePublished\":\"2026-07-23T07:43:43+00:00\",\"dateModified\":\"2026-07-23T07:45:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/\"},\"wordCount\":1204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/invertir-en-vivienda-en-Valencia.webp\",\"keywords\":[\"Comunidad Valenciana\",\"crowdfunding immobilier\",\"financement participatif sous forme de capital\",\"investissement immobilier\",\"secteur r\u00e9sidentiel\"],\"articleSection\":[\"Equity\",\"Projets\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/\",\"name\":\"Investir dans le logement \u00e0 Valence : Mirador Sur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/invertir-en-vivienda-en-Valencia.webp\",\"datePublished\":\"2026-07-23T07:43:43+00:00\",\"dateModified\":\"2026-07-23T07:45:34+00:00\",\"description\":\"D\u00e9couvrez comment investir dans le logement \u00e0 Valence avec Mirador Sur : 240 logements \u00e0 Albal, TRI pr\u00e9f\u00e9rentiel de 21,15 % et financement bancaire pr\u00e9vu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/invertir-en-vivienda-en-Valencia.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/invertir-en-vivienda-en-Valencia.webp\",\"width\":1400,\"height\":735,\"caption\":\"Invertir en vivienda en Valencia: Mirador Sur. Invest in residential property in Valencia: Mirador Sur. Investir dans le logement \u00e0 Valence : Mirador Sur. Investire in abitazioni a Valencia: Mirador Sur. Investir em habita\u00e7\u00e3o em Val\u00eancia: Mirador Sur. In Wohnimmobilien in Valencia investieren: Mirador Sur.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/2026\\\/07\\\/23\\\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mirador Sur : plus-value pour 240 logements \u00e0 Albal, Valence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"L'investissement immobilier \u00e0 la port\u00e9e de tous\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/fr\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investir dans le logement \u00e0 Valence : Mirador Sur","description":"D\u00e9couvrez comment investir dans le logement \u00e0 Valence avec Mirador Sur : 240 logements \u00e0 Albal, TRI pr\u00e9f\u00e9rentiel de 21,15 % et financement bancaire pr\u00e9vu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/","og_locale":"fr_FR","og_type":"article","og_title":"Mirador Sur : 240 logements dans l'aire m\u00e9tropolitaine de Valence","og_description":"Nouvelle opportunit\u00e9 de plus-value \u00e0 Albal, \u00e0 moins de 10 kilom\u00e8tres de Valence, avec 240 logements r\u00e9partis dans trois tours et un TRI pr\u00e9f\u00e9rentiel pour les investisseurs.","og_url":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/","og_site_name":"Urbanitae Blog | Les meilleures nouvelles sur l'investissement immobilier","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2026-07-23T07:43:43+00:00","article_modified_time":"2026-07-23T07:45:34+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"\u00c9crit par":"Equipo Urbanitae","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/fr\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Mirador Sur : plus-value pour 240 logements \u00e0 Albal, Valence","datePublished":"2026-07-23T07:43:43+00:00","dateModified":"2026-07-23T07:45:34+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/"},"wordCount":1204,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp","keywords":["Comunidad Valenciana","crowdfunding immobilier","financement participatif sous forme de capital","investissement immobilier","secteur r\u00e9sidentiel"],"articleSection":["Equity","Projets"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/","url":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/","name":"Investir dans le logement \u00e0 Valence : Mirador Sur","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp","datePublished":"2026-07-23T07:43:43+00:00","dateModified":"2026-07-23T07:45:34+00:00","description":"D\u00e9couvrez comment investir dans le logement \u00e0 Valence avec Mirador Sur : 240 logements \u00e0 Albal, TRI pr\u00e9f\u00e9rentiel de 21,15 % et financement bancaire pr\u00e9vu.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2026\/07\/invertir-en-vivienda-en-Valencia.webp","width":1400,"height":735,"caption":"Invertir en vivienda en Valencia: Mirador Sur. Invest in residential property in Valencia: Mirador Sur. Investir dans le logement \u00e0 Valence : Mirador Sur. Investire in abitazioni a Valencia: Mirador Sur. Investir em habita\u00e7\u00e3o em Val\u00eancia: Mirador Sur. In Wohnimmobilien in Valencia investieren: Mirador Sur."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/fr\/2026\/07\/23\/mirador-sur-plus-value-pour-240-logements-a-albal-valence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Mirador Sur : plus-value pour 240 logements \u00e0 Albal, Valence"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/fr\/#website","url":"https:\/\/blog.urbanitae.com\/fr\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"L'investissement immobilier \u00e0 la port\u00e9e de tous","publisher":{"@id":"https:\/\/blog.urbanitae.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/fr\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.urbanitae.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/fr\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/fr\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/posts\/89212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/comments?post=89212"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/posts\/89212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/media\/89211"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/media?parent=89212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/categories?post=89212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/fr\/wp-json\/wp\/v2\/tags?post=89212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}