{"id":77928,"date":"2025-12-29T08:45:00","date_gmt":"2025-12-29T07:45:00","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=77928"},"modified":"2025-12-26T14:48:21","modified_gmt":"2025-12-26T13:48:21","slug":"wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/","title":{"rendered":"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bei <strong>Urbanitae<\/strong> haben wir 2025 mit einer Zahl abgeschlossen, die die Entwicklung unseres Modells am besten zusammenfasst: <strong>im Laufe des Jahres haben wir 97 Millionen Euro an unsere Investoren zur\u00fcckgezahlt<\/strong>, aus bereits abgeschlossenen Projekten. Dieses Volumen bedeutet <strong>ein Wachstum von 142,5 % im Vergleich zu 2024<\/strong>, als die R\u00fcckzahlungen 40 Millionen Euro betrugen.<br>Es handelt sich nicht nur um eine Rekordzahl, sondern auch um ein klares Signal daf\u00fcr, dass unser Projektportfolio ein zunehmend h\u00f6heres Reifegradniveau erreicht hat. Hinter diesem Wachstum steht die kontinuierliche Arbeit der letzten Jahre, intensive Finanzierungst\u00e4tigkeit und ein Modell, das darauf ausgelegt ist, den Investor w\u00e4hrend des gesamten Immobilieninvestitionszyklus zu begleiten \u2013 vom Einstieg in das Projekt bis zur R\u00fcckzahlung des Kapitals und der erzielten Rendite.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fast 180 Millionen Euro insgesamt zur\u00fcckgezahlt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn man die Perspektive erweitert und alle seit unserer Gr\u00fcndung geleisteten Gesamt- und Teilr\u00fcckzahlungen zusammenz\u00e4hlt, hat <strong>Urbanitae bereits 179 Millionen Euro an unsere Investoren zur\u00fcckgezahlt<\/strong>. Diese Zahl zeigt nicht nur das Volumen der Projekte, die ihre Exit-Phase erreicht haben, sondern auch unsere F\u00e4higkeit, Fristen und geplante Ziele in einem weiterhin anspruchsvollen Umfeld f\u00fcr den Immobiliensektor einzuhalten.<br>Die progressive Beschleunigung der R\u00fcckzahlungen ist zudem eine logische Folge des Wachstums der Plattform. Mit zunehmender Anzahl finanzierter Projekte und deren Fortschreiten im Entwicklungsprozess steigt auch die Anzahl der Operationen, die f\u00e4llig werden, wodurch das Gewicht der R\u00fcckzahlungen innerhalb unserer Gesamtaktivit\u00e4t gest\u00e4rkt wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Durchschnittliche Rentabilit\u00e4t im Einklang mit den Zielen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/\" target=\"_blank\" rel=\"noreferrer noopener\">Das im Jahr 2025 zur\u00fcckgezahlte Kapital<\/a> wurde unter <strong>mehr als 43.000 Investoren<\/strong> verteilt, mit einem Durchschnitt von \u00fcber 600 Teilnehmern pro Projekt. Seit unserer Gr\u00fcndung haben wir <strong>\u00fcber 240.000 Investitionen<\/strong> get\u00e4tigt, was uns erm\u00f6glicht, diversifizierten Zugang zu gro\u00dfvolumigen Immobilienprojekten zu bieten, die traditionell professionellen oder institutionellen Investoren vorbehalten sind.<br>Bez\u00fcglich der Rentabilit\u00e4t haben die Projekte, die R\u00fcckzahlungen generiert haben, <strong>eine durchschnittliche j\u00e4hrliche Rendite von 12,3 %<\/strong> erreicht, im Einklang mit dem zu Beginn jeder Operation definierten Ziel-IRR. Dies best\u00e4tigt, dass die aggregierte Performance des Portfolios innerhalb der erwarteten Parameter bleibt, selbst in einem Umfeld, das von der Normalisierung der M\u00e4rkte und einem selektiveren Finanzumfeld gepr\u00e4gt ist.<br>Nach Typologie stammt der Gro\u00dfteil des zur\u00fcckgezahlten Kapitals aus <strong>projekten, die als Fremdkapital strukturiert sind<\/strong>, mit durchschnittlichen Laufzeiten von rund 13 Monaten, was Sichtbarkeit und Regelm\u00e4\u00dfigkeit der R\u00fcckzahlungen bietet. Der Rest entf\u00e4llt auf <strong><a href=\"https:\/\/blog.urbanitae.com\/de\/2025\/12\/07\/unterschiede-zwischen-debt-und-equity-zwei-wege-in-immobilien-crowdfunding-zu-investieren\/\" target=\"_blank\" rel=\"noreferrer noopener\">Equity-Operationen<\/a><\/strong>, die mit l\u00e4ngeren Zeithorizonten und der vollst\u00e4ndigen Entwicklung der Projekte verbunden sind \u2013 von der Akquisition bis zum endg\u00fcltigen Verkauf der Immobilie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Madrid f\u00fchrt<\/strong> <strong>die R\u00fcckzahlungen an<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Geografisch betrachtet konzentriert die<a href=\"https:\/\/www.eleconomista.es\/vivienda-inmobiliario\/noticias\/13577462\/10\/25\/madrid-ya-es-la-segunda-ciudad-europea-mas-sexy-para-la-inversion-inmobiliaria.html\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>Region Madrid<\/strong><\/a> weiterhin einen erheblichen Teil der R\u00fcckzahlungen, gefolgt von <strong>Andalusien, den Balearen und Katalonien<\/strong>. Dies sind M\u00e4rkte, in denen wir eine hohe Entwicklungsaktivit\u00e4t aufrechterhalten und Projekte in verschiedenen Phasen der Ausf\u00fchrung, Vermarktung und des Exits haben.<br>Diese territoriale Diversifizierung ist Teil unseres Risikomanagementansatzes. Sie erm\u00f6glicht es uns, das Portfolio auszugleichen, die Exposition gegen\u00fcber spezifischen lokalen Dynamiken zu reduzieren und Chancen in verschiedenen Immobilienm\u00e4rkten mit ihren eigenen Verhaltensweisen und Zyklen zu nutzen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine Zahl, die unser Engagement gegen\u00fcber Investoren st\u00e4rkt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das hohe R\u00fcckzahlungsvolumen, das im letzten Abschnitt von 2025 verzeichnet wurde, und die Tatsache, dass wir die Zahlen des Vorjahres mehr als verdoppelt haben, best\u00e4tigen, dass unser Projektportfolio ein signifikantes Reifegradniveau erreicht hat. In einem komplexen Umfeld zeigt der Immobiliensektor weiterhin seine F\u00e4higkeit, mittel- und langfristig Wert zu schaffen, und bei Urbanitae erf\u00fcllen wir weiterhin unser grundlegendes Versprechen: <strong>Kapital zur\u00fcckzahlen und <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/01\/17\/unser-ziel-ist-es-dass-jeder-investor-teil-von-urbanitae-werden-kann\/\" target=\"_blank\" rel=\"noreferrer noopener\">unseren Investoren<\/a> attraktive Renditen p\u00fcnktlich und vollst\u00e4ndig bieten<\/strong>.<br>So schlie\u00dfen wir das Gesch\u00e4ftsjahr auf einer soliden Basis ab, auf der wir weiter aufbauen k\u00f6nnen. Sobald die in den letzten Jahren finanzierten neuen Projekte ihre Endphase erreichen, werden die R\u00fcckzahlungen weiterhin an Bedeutung gewinnen und ein Modell st\u00e4rken, das auf Transparenz, kontinuierliche \u00dcberwachung und Interessenangleichung zwischen Projektentwicklern und Investoren setzt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2025 haben wir 97 Millionen \u20ac an \u00fcber 43.000 Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen j\u00e4hrlichen Rendite von 12,3 %, was die Reife und St\u00e4rke unseres Portfolios widerspiegelt.<\/p>\n","protected":false},"author":1,"featured_media":78050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1686,1699,1714],"tags":[1965,2176,836,1745,2184],"class_list":["post-77928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immobilieninvestition-de","category-projekte","category-urbanitae-de","tag-immobilien-crowdfunding","tag-immobilieninvestition","tag-investition","tag-urbanitae-de","tag-wohnimmobiliensektor"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!<\/title>\n<meta name=\"description\" content=\"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projekt-R\u00fcckzahlungen 2025: 97 Millionen \u20ac an unsere Investoren zur\u00fcckgegeben\" \/>\n<meta property=\"og:description\" content=\"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-29T07:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!\",\"datePublished\":\"2025-12-29T07:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Destacada-blog-4.webp\",\"keywords\":[\"Immobilien Crowdfunding\",\"Immobilieninvestition\",\"Investition\",\"Urbanitae\",\"Wohnimmobiliensektor\"],\"articleSection\":[\"Immobilieninvestition\",\"Projekte\",\"Urbanitae\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/\",\"name\":\"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Destacada-blog-4.webp\",\"datePublished\":\"2025-12-29T07:45:00+00:00\",\"description\":\"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Destacada-blog-4.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Destacada-blog-4.webp\",\"width\":1400,\"height\":735,\"caption\":\"Rozamos los 100 millones de euros en devoluciones solo en 2025 We\u2019re Approaching \u20ac100 Million in Returns in 2025 Alone Nous fr\u00f4lons les 100 millions d\u2019euros de remboursements en 2025 Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein im Jahr 2025 Sfioriamo i 100 milioni di euro di rimborsi solo nel 2025 Cheg\u00e1mos perto de 100 milh\u00f5es de euros em reembolsos s\u00f3 em 2025\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/12\\\/29\\\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Inversi\u00f3n inmobiliaria al alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!","description":"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/","og_locale":"de_DE","og_type":"article","og_title":"Projekt-R\u00fcckzahlungen 2025: 97 Millionen \u20ac an unsere Investoren zur\u00fcckgegeben","og_description":"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.","og_url":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/","og_site_name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-12-29T07:45:00+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Verfasst von":"Equipo Urbanitae","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!","datePublished":"2025-12-29T07:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp","keywords":["Immobilien Crowdfunding","Immobilieninvestition","Investition","Urbanitae","Wohnimmobiliensektor"],"articleSection":["Immobilieninvestition","Projekte","Urbanitae"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/","url":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/","name":"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp","datePublished":"2025-12-29T07:45:00+00:00","description":"Urbanitae zahlt 2025 97 Millionen \u20ac an Investoren zur\u00fcck \u2013 so sorgt unser Portfolio f\u00fcr Rendite und Vertrauen.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/12\/Destacada-blog-4.webp","width":1400,"height":735,"caption":"Rozamos los 100 millones de euros en devoluciones solo en 2025 We\u2019re Approaching \u20ac100 Million in Returns in 2025 Alone Nous fr\u00f4lons les 100 millions d\u2019euros de remboursements en 2025 Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein im Jahr 2025 Sfioriamo i 100 milioni di euro di rimborsi solo nel 2025 Cheg\u00e1mos perto de 100 milh\u00f5es de euros em reembolsos s\u00f3 em 2025"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/de\/2025\/12\/29\/wir-naehern-uns-100-millionen-euro-an-rueckzahlungen-allein-in-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wir n\u00e4hern uns 100 Millionen Euro an R\u00fcckzahlungen allein in 2025!"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/de\/#website","url":"https:\/\/blog.urbanitae.com\/de\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Inversi\u00f3n inmobiliaria al alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/de\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/de\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/77928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/comments?post=77928"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/77928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media\/78050"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media?parent=77928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/categories?post=77928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/tags?post=77928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}