{"id":70344,"date":"2025-09-25T12:26:29","date_gmt":"2025-09-25T10:26:29","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=70344"},"modified":"2025-09-25T13:22:26","modified_gmt":"2025-09-25T11:22:26","slug":"urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/","title":{"rendered":"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bei Urbanitae haben wir einen neuen Meilenstein erreicht: Wir haben bereits mehr als <strong>100 Millionen Euro<\/strong> an unsere Investoren zur\u00fcckgezahlt. Konkret belaufen sich die R\u00fcckzahlungen auf 105,1 Millionen Euro aus <strong>68 erfolgreich abgeschlossenen Projekten<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn es um Investitionen geht, gibt es kein besseres Ma\u00df f\u00fcr den Erfolg als die tats\u00e4chlich erzielte Rendite. Insgesamt sprechen wir von einer IRR von \u00fcber 12 %, im Einklang mit der Zielrendite des gesamten Portfolios, das sowohl Wertsteigerungsprojekte als auch Schuldprojekte umfasst. Wichtig ist, dass wir nur die R\u00fcckzahlungen von vollst\u00e4ndig abgeschlossenen Projekten ber\u00fccksichtigen und keine Teilr\u00fcckzahlungen einbeziehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insgesamt haben mehr als <strong>40.000 Investoren<\/strong> ihr Kapital samt <a href=\"https:\/\/blog.urbanitae.com\/de\/2025\/02\/11\/wie-erkennt-man-ob-eine-investition-rentabel-ist-ueber-die-gebuehren-hinaus\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rendite<\/a> aus einem der abgeschlossenen Projekte zur\u00fcckerhalten. Jedes zur\u00fcckgezahlte Projekt umfasste im Durchschnitt etwa 600 Investoren, und seit unserer Gr\u00fcndung haben wir bereits mehr als <strong>200.000 Investitionen<\/strong> verwaltet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser Erfolg festigt unsere Position als eine der f\u00fchrenden Crowdfunding-Plattformen Europas im Hinblick auf Kapitalr\u00fcckzahlungen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Renditen im Einklang mit den Prognosen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die <strong>durchschnittliche Jahresrendite<\/strong> der zur\u00fcckgezahlten Projekte liegt bei <strong>12,2 %<\/strong>, im Einklang mit der zu Beginn festgelegten <strong>Ziel-<a href=\"https:\/\/blog.urbanitae.com\/de\/2025\/05\/30\/was-sind-projekte-mit-bevorrechtigtem-irr-bei-urbanitae\/\" target=\"_blank\" rel=\"noreferrer noopener\">IRR<\/a><\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>61 % des zur\u00fcckgezahlten Kapitals<\/strong> stammen aus <strong>Schuldprojekten<\/strong> mit einer durchschnittlichen Laufzeit von 13 Monaten.<\/li>\n\n\n\n<li>Die <strong>restlichen 39 %<\/strong> entfallen auf <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/09\/06\/welche-arten-von-equity-projekten-gibt-es-bei-urbanitae\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eigenkapitalprojekte<\/a> mit l\u00e4ngeren durchschnittlichen Laufzeiten von etwa 29 Monaten.<\/li>\n\n\n\n<li>Dar\u00fcber hinaus haben unsere Mietprojekte \u2013 basierend auf vermieteten Immobilien wie Superm\u00e4rkten und Buchhandlungen \u2013 den Investoren fast 1 Million Euro zur\u00fcckgezahlt, mit einer j\u00e4hrlichen Nettorendite von 5,4 %, ebenfalls im Einklang mit den Erwartungen.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Fast die H\u00e4lfte der zur\u00fcckgezahlten Projekte befindet sich in der <strong>Autonomen Gemeinschaft Madrid<\/strong>, die mehr als <strong>45 Millionen Euro<\/strong> ausmacht. Es folgen <strong>Andalusien<\/strong> mit 15,2 Millionen Euro aus 12 Projekten (vor allem in M\u00e1laga), die <strong>Balearen<\/strong> mit \u00fcber 14 Millionen Euro aus f\u00fcnf Projekten und <strong>Katalonien<\/strong> mit 13,6 Millionen Euro aus acht <a href=\"https:\/\/urbanitae.com\/en\/projects\" target=\"_blank\" rel=\"noreferrer noopener\">Projekten<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wenn die Realit\u00e4t den Businessplan \u00fcbertrifft<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nicht alle Eigenkapitalprojekte haben in Bezug auf Zeitpl\u00e4ne und Renditen dem urspr\u00fcnglichen Plan entsprochen. Der abrupte Anstieg der Baukosten, Verz\u00f6gerungen durch die globale Logistikkrise nach Covid, die Auswirkungen des Krieges in der Ukraine auf Rohstoffe wie Treibstoff und Aluminium sowie steigende Zinss\u00e4tze haben den Immobiliensektor auf die Probe gestellt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie <a href=\"https:\/\/blog.urbanitae.com\/de\/2025\/09\/24\/es-gibt-keine-immobilienblase-aber-die-preise-koennen-nicht-ewig-steigen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Diego Bestard<\/a>, CEO von Urbanitae, erkl\u00e4rt:<br>\u201eWir hatten eine Generation von Projekten \u2013 insbesondere in den Jahren 2021, 2022 und teilweise 2023 \u2013 die durch au\u00dfergew\u00f6hnliche Faktoren stark beeintr\u00e4chtigt wurde. Einige von ihnen haben die erwartete Rentabilit\u00e4t nicht erreicht und erhebliche Verz\u00f6gerungen erlitten. Aber das Entscheidende ist, dass wir trotz dieses perfekten Sturms von Variablen <strong>in keinem Projekt Kapital verloren haben<\/strong>. Wenn das schlimmste Szenario darin besteht, das investierte Kapital zur\u00fcckzuerhalten, ist das ein Gewinn. Das bedeutet, dass unser Risikomanagementmodell funktioniert.\u201c<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Urbanitae in Zahlen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seit 2019 haben wir Immobilienprojekte im Wert von \u00fcber <strong>530 Millionen Euro<\/strong> finanziert, davon mehr als 200 Millionen allein im Jahr 2024. Damit haben wir zum Bau von \u00fcber <strong>7.100 Wohnungen<\/strong> in Spanien und Portugal beigetragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und das ist erst der Anfang: Wir arbeiten weiterhin daran, neue Investitionsm\u00f6glichkeiten zu er\u00f6ffnen, die es immer mehr Menschen erm\u00f6glichen, <strong>einfach, 100 % online und mit beiden Beinen auf dem Boden in gro\u00dfe Immobilienprojekte zu investieren<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir haben die R\u00fcckzahlung von 68 Projekten abgeschlossen \u2013 ohne Verluste bei einem einzigen \u2013 und mit einer durchschnittlichen IRR von \u00fcber 12 %.<\/p>\n","protected":false},"author":1,"featured_media":70308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1686,1714],"tags":[1965,1954,2176,2175,1745],"class_list":["post-70344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immobilieninvestition-de","category-urbanitae-de","tag-immobilien-crowdfunding","tag-immobilien-crowdlending","tag-immobilieninvestition","tag-rendite","tag-urbanitae-de"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren<\/title>\n<meta name=\"description\" content=\"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Positive Rendite in 100 % der Projekte\" \/>\n<meta property=\"og:description\" content=\"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-25T10:26:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T11:22:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren\",\"datePublished\":\"2025-09-25T10:26:29+00:00\",\"dateModified\":\"2025-09-25T11:22:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/\"},\"wordCount\":509,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/urbanitae-devoluciones-inversores.jpg\",\"keywords\":[\"Immobilien Crowdfunding\",\"Immobilien Crowdlending\",\"Immobilieninvestition\",\"Rendite\",\"Urbanitae\"],\"articleSection\":[\"Immobilieninvestition\",\"Urbanitae\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/\",\"name\":\"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/urbanitae-devoluciones-inversores.jpg\",\"datePublished\":\"2025-09-25T10:26:29+00:00\",\"dateModified\":\"2025-09-25T11:22:26+00:00\",\"description\":\"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/urbanitae-devoluciones-inversores.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/urbanitae-devoluciones-inversores.jpg\",\"width\":1400,\"height\":735,\"caption\":\"Urbanitae supera los 100 millones de euros en devoluciones a inversores. \\u0016Urbanitae surpasses \u20ac100 million in returns to investors. Urbanitae d\u00e9passe les 100 millions d\u2019euros de remboursements aux investisseurs. Urbanitae supera i 100 milioni di euro in restituzioni agli investitori. Urbanitae supera os 100 milh\u00f5es de euros em devolu\u00e7\u00f5es a investidores. Urbanitae \u00fcbertrifft 100 Millionen Euro an R\u00fcckzahlungen an Investoren.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2025\\\/09\\\/25\\\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Inversi\u00f3n inmobiliaria al alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren","description":"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/","og_locale":"de_DE","og_type":"article","og_title":"Positive Rendite in 100 % der Projekte","og_description":"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.","og_url":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/","og_site_name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2025-09-25T10:26:29+00:00","article_modified_time":"2025-09-25T11:22:26+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg","type":"image\/jpeg"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Verfasst von":"Equipo Urbanitae","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren","datePublished":"2025-09-25T10:26:29+00:00","dateModified":"2025-09-25T11:22:26+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/"},"wordCount":509,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg","keywords":["Immobilien Crowdfunding","Immobilien Crowdlending","Immobilieninvestition","Rendite","Urbanitae"],"articleSection":["Immobilieninvestition","Urbanitae"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/","url":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/","name":"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg","datePublished":"2025-09-25T10:26:29+00:00","dateModified":"2025-09-25T11:22:26+00:00","description":"Bei Urbanitae haben wir \u00fcber 100 Mio. \u20ac an Investoren zur\u00fcckgezahlt, mit einer durchschnittlichen Jahresrendite von \u00fcber 12 %. Mehr erfahren.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2025\/09\/urbanitae-devoluciones-inversores.jpg","width":1400,"height":735,"caption":"Urbanitae supera los 100 millones de euros en devoluciones a inversores. \u0016Urbanitae surpasses \u20ac100 million in returns to investors. Urbanitae d\u00e9passe les 100 millions d\u2019euros de remboursements aux investisseurs. Urbanitae supera i 100 milioni di euro in restituzioni agli investitori. Urbanitae supera os 100 milh\u00f5es de euros em devolu\u00e7\u00f5es a investidores. Urbanitae \u00fcbertrifft 100 Millionen Euro an R\u00fcckzahlungen an Investoren."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/de\/2025\/09\/25\/urbanitae-ueberschreitet-100-mio-e-an-rueckzahlungen-an-investoren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/de\/"},{"@type":"ListItem","position":2,"name":"Urbanitae \u00fcberschreitet 100 Mio. \u20ac an R\u00fcckzahlungen an Investoren"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/de\/#website","url":"https:\/\/blog.urbanitae.com\/de\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Inversi\u00f3n inmobiliaria al alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/de\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/de\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/70344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/comments?post=70344"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/70344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media\/70308"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media?parent=70344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/categories?post=70344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/tags?post=70344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}