{"id":51331,"date":"2024-10-14T17:34:39","date_gmt":"2024-10-14T15:34:39","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=51331"},"modified":"2024-10-18T15:35:30","modified_gmt":"2024-10-18T13:35:30","slug":"neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/","title":{"rendered":"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5%"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"51331\" class=\"elementor elementor-51331 elementor-51320\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-84cc9ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84cc9ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2e2fe2c7\" data-id=\"2e2fe2c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42bca508 elementor-widget elementor-widget-text-editor\" data-id=\"42bca508\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p>Wir pr\u00e4sentieren ein neues Projekt auf der Plattform, das f\u00fcnfte im Oktober und das erste auf Fremdkapitalbasis. Dieses Mal kehren wir in die Region Madrid zur\u00fcck, um in sozialen Wohnungsbau mit einer Rendite von 11,5% \u00fcber 12 Monate zu investieren. Die Finanzierung f\u00fcr das Projekt startet <strong>am kommenden Freitag, den 18. Oktober um 12 Uhr (UTC+2).<\/strong> Interessiert? Hier sind alle Details.<\/p>\n<p> <\/p>\n<p>Das Projekt <a href=\"https:\/\/urbanitae.com\/en\/project\/P000322?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1024&amp;utm_term=balcon_del_sur_1&amp;utm_content=de_proyecto_balcon_del_sur\" target=\"_blank\" rel=\"noreferrer noopener\">Balc\u00f3n del Sur<\/a> besteht in der <strong>Vergabe eines \u00dcberbr\u00fcckungskredits<\/strong> zur Teilfinanzierung des Kaufs eines Grundst\u00fccks in Navalcarnero, Madrid, f\u00fcr die Entwicklung eines <strong>Wohnprojekts in genossenschaftlicher Form mit 144 Wohnungen im Rahmen des \u00f6ffentlich gef\u00f6rderten Wohnungsbaus (VPPL).<\/strong><\/p>\n<p> <\/p>\n<p>Die 144 VPPL-Wohnungen verf\u00fcgen \u00fcber drei Schlafzimmer, zwei Badezimmer, gro\u00dfe Terrassen und weitl\u00e4ufige Gemeinschaftsbereiche mit Pool, Innenhof und Privatgarten. Das Projekt liegt weniger als 30 km vom Zentrum Madrids entfernt; mit dem Auto dauert die Fahrt 25 Minuten \u00fcber die A-5 oder R-5, au\u00dferdem ist es gut an den Busverkehr angebunden. <strong>Navalcarnero ist eine Stadt mit starkem Immobilienwachstum<\/strong> und wird als erschwingliche und ruhige Alternative nahe Madrid angesehen. Seit 2018 ist die Bev\u00f6lkerung um 13% gewachsen.<\/p>\n<p> <\/p>\n<p>Der Projektentwickler von Balc\u00f3n del Sur ist Urbanismo y Gesti\u00f3n, ein Unternehmen mit fast 40 Jahren Erfahrung in der Branche und <strong>mehr als 9.000 fertiggestellten Wohnungen.<\/strong> Allein in Madrid hat der Entwickler \u00fcber 50 Projekte in genossenschaftlicher Form realisiert, was etwa 1.800 Wohnungen entspricht. <strong>Balc\u00f3n del Sur ist sein zweites Projekt in Navalcarnero, nach dem Erfolg der ersten Entwicklung<\/strong> mit 102 Einheiten, die derzeit zu 100% verkauft und in der Schl\u00fcssel\u00fcbergabephase ist.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">11,5% Rendite in 12 Monaten<\/h2>\n<p> <\/p>\n<p>Das Projekt <a href=\"https:\/\/urbanitae.com\/en\/project\/P000322?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1024&amp;utm_term=balcon_del_sur_2&amp;utm_content=de_proyecto_balcon_del_sur\" target=\"_blank\" rel=\"noreferrer noopener\">Balc\u00f3n del Sur<\/a> basiert auf einer Fremdkapitalstrategie. Die Urbanitae-Investoren beteiligen sich am Projekt durch die Vergabe eines <strong>einzigen Kredits mit einem festen j\u00e4hrlichen Zinssatz von 11,50% \u00fcber 12 Monate,<\/strong> um den Grundst\u00fcckskauf teilweise zu finanzieren. <strong>Der Ausstieg der Urbanitae-Investoren erfolgt durch eine Bankrefinanzierung<\/strong> nach Erreichen von zwei Meilensteinen: (i) der Genehmigung der Baugenehmigung und (ii) dem Erreichen von 70% Verkaufsfortschritt \u2013 100 verkaufte Einheiten.<\/p>\n<p> <\/p>\n<p>Urbanismo y Gesti\u00f3n bringt rund 2,85 Millionen Euro in den Kauf ein, was 35% des Kaufpreises ausmacht.<\/p>\n<p> <\/p>\n<p>Die Baugenehmigung liegt noch nicht vor, wird aber vor Jahresende beantragt, und der Entwickler erwartet, dass die Genehmigung in etwa 5 bis 6 Monaten erteilt wird, basierend auf seinen Erfahrungen mit der Stadtverwaltung von Navalcarnero.<\/p>\n<p> <\/p>\n<h2 class=\"wp-block-heading\">Hypothekengarantie und Mindestlaufzeit von 12 Monaten<\/h2>\n<p> <\/p>\n<p>Das Gesamtvolumen des Kredits betr\u00e4gt bis zu 5.370.000 Euro: 5.000.000 Euro werden \u00fcber die Plattform von Urbanitae-Investoren finanziert, der Rest durch externe Investoren.<\/p>\n<p> <\/p>\n<p>Eine vorzeitige R\u00fcckzahlung des gesamten Kredits ist jederzeit m\u00f6glich, <strong>vorbehaltlich einer garantierten Mindestverzinsung des Kredits, die einem Zins von 12 Monaten entspricht.<\/strong> Eine Verl\u00e4ngerung um weitere sechs Monate nach dem 12. Monat ist m\u00f6glich.<\/p>\n<p> <\/p>\n<p>Hinsichtlich der <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1024&amp;utm_term=ruckzahlungsgarantien&amp;utm_content=de_proyecto_balcon_del_sur\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00fcckzahlungsgarantien<\/a> f\u00fcr den Kredit ist im Kreditvertrag eine <strong>Grundschuld erster Rang auf das zum Projekt geh\u00f6rende Grundst\u00fcck<\/strong> durch einen Treuh\u00e4nder festgelegt.<\/p>\n<p> <\/p>\n<p>In diesem Video erkl\u00e4ren der Entwickler und unser Direktor f\u00fcr Immobilien, Sergio Arana, die wichtigsten Aspekte des Projekts <a href=\"https:\/\/urbanitae.com\/en\/project\/P000322?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_1024&amp;utm_term=balcon_del_sur_3&amp;utm_content=de_proyecto_balcon_del_sur\" target=\"_blank\" rel=\"noreferrer noopener\">Balc\u00f3n del Sur<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-fcce5c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcce5c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-316ef7c\" data-id=\"316ef7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2df4557 elementor-widget elementor-widget-video\" data-id=\"2df4557\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/BUeonfF7W7Q&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-6d3a1e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3a1e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2bacf90\" data-id=\"2bacf90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b39a3a9 elementor-widget elementor-widget-text-editor\" data-id=\"b39a3a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"wp-block-heading\">Rendite im Oktober 2025<\/h2>\n<p> <\/p>\n<p>Die geplante Laufzeit dieses Projekts betr\u00e4gt bis zu 12 Monate mit einer m\u00f6glichen Verl\u00e4ngerung um 6 Monate nach dem 12. Monat. Die Baugenehmigung wird f\u00fcr Juni bis August 2025 erwartet, und die 70% Verkaufsquote soll zwischen August und September desselben Jahres erreicht werden. Die Bankrefinanzierung des Urbanitae-Darlehens und damit der Ausstieg der Investoren wird im Oktober 2025 erfolgen.<\/p>\n<p> <\/p>\n<p>Hast du Fragen? Stell sie uns im <strong><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_9y6K1YlRQ-a7XPH3jZiVQg\" target=\"_blank\" rel=\"noreferrer noopener\">Webinar<\/a><\/strong> mit dem Entwickler am kommenden <strong>Mittwoch, den 16. Oktober um 12 Uhr (UTC+2).<\/strong> Du kannst uns auch unter <a href=\"mailto:contacto@urbanitae.com\" target=\"_blank\" rel=\"noreferrer noopener\">contacto@urbanitae.com<\/a> und (+34) 911 23 25 22 erreichen.<\/p>\n<p> <\/p>\n<p>Verpasse nicht die Gelegenheit, in sozialen Wohnungsbau mit einer Rendite von 11,5% \u00fcber 12 Monate zu investieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Das Projekt Balc\u00f3n del Sur umfasst die Gew\u00e4hrung eines 12-monatigen \u00dcberbr\u00fcckungskredits zur Finanzierung eines Grundst\u00fccks, auf dem 144 gef\u00f6rderte Wohnungen im Rahmen einer Genossenschaft entstehen werden.<\/p>\n","protected":false},"author":1,"featured_media":51362,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1699,1700],"tags":[2010,1965,1954],"class_list":["post-51331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-projekte","category-schulden","tag-edilizia-convenzionata","tag-immobilien-crowdfunding","tag-immobilien-crowdlending"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5% - Urbanitae Blog<\/title>\n<meta name=\"description\" content=\"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investiere in sozialen Wohnungsbau ab 500 Euro\" \/>\n<meta property=\"og:description\" content=\"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-14T15:34:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-18T13:35:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5%\",\"datePublished\":\"2024-10-14T15:34:39+00:00\",\"dateModified\":\"2024-10-18T13:35:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/invierte-vivienda-protegida.webp\",\"keywords\":[\"edilizia convenzionata\",\"Immobilien Crowdfunding\",\"Immobilien Crowdlending\"],\"articleSection\":[\"Projekte\",\"Schulden\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/\",\"name\":\"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5% - Urbanitae Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/invierte-vivienda-protegida.webp\",\"datePublished\":\"2024-10-14T15:34:39+00:00\",\"dateModified\":\"2024-10-18T13:35:30+00:00\",\"description\":\"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/invierte-vivienda-protegida.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/invierte-vivienda-protegida.webp\",\"width\":1400,\"height\":735,\"caption\":\"Invierte en vivienda protegida. Invest in affordable housing. Investissez dans des logements prot\u00e9g\u00e9s. Investi in alloggi a prezzi calmierati. Invista em habita\u00e7\u00e3o protegida. Investiere in sozialen Wohnungsbau\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/10\\\/14\\\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Inversi\u00f3n inmobiliaria al alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5% - Urbanitae Blog","description":"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/","og_locale":"de_DE","og_type":"article","og_title":"Investiere in sozialen Wohnungsbau ab 500 Euro","og_description":"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.","og_url":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/","og_site_name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2024-10-14T15:34:39+00:00","article_modified_time":"2024-10-18T13:35:30+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Verfasst von":"Equipo Urbanitae","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5%","datePublished":"2024-10-14T15:34:39+00:00","dateModified":"2024-10-18T13:35:30+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp","keywords":["edilizia convenzionata","Immobilien Crowdfunding","Immobilien Crowdlending"],"articleSection":["Projekte","Schulden"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/","url":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/","name":"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5% - Urbanitae Blog","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp","datePublished":"2024-10-14T15:34:39+00:00","dateModified":"2024-10-18T13:35:30+00:00","description":"Investiere in gef\u00f6rdeten Wohnraum ab 500 Euro mit Urbanitae, mit einer Rendite von 11,5 % in 12 Monaten. Alle Details hier.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/10\/invierte-vivienda-protegida.webp","width":1400,"height":735,"caption":"Invierte en vivienda protegida. Invest in affordable housing. Investissez dans des logements prot\u00e9g\u00e9s. Investi in alloggi a prezzi calmierati. Invista em habita\u00e7\u00e3o protegida. Investiere in sozialen Wohnungsbau"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/10\/14\/neues-projekt-investiere-in-geforderten-wohnraum-mit-einer-jahrlichen-rendite-von-115\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/de\/"},{"@type":"ListItem","position":2,"name":"Investiere in gef\u00f6rderten Wohnraum mit einer j\u00e4hrlichen Rendite von 11,5%"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/de\/#website","url":"https:\/\/blog.urbanitae.com\/de\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Inversi\u00f3n inmobiliaria al alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/de\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/de\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/51331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/comments?post=51331"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/51331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media\/51362"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media?parent=51331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/categories?post=51331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/tags?post=51331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}