{"id":46249,"date":"2024-07-12T14:53:22","date_gmt":"2024-07-12T12:53:22","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=46249"},"modified":"2024-07-12T14:54:37","modified_gmt":"2024-07-12T12:54:37","slug":"investieren-sie-mit-einer-rendite-von-105-in-12-monaten","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/","title":{"rendered":"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"46249\" class=\"elementor elementor-46249 elementor-46237\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-451a2e7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"451a2e7d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45d2152\" data-id=\"45d2152\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6541281d elementor-widget elementor-widget-text-editor\" data-id=\"6541281d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>Wir sind mit einem neuen Schuldenprojekt bei Urbanitae zur\u00fcck. Am n\u00e4chsten <strong>Dienstag, den 16. Juli um 16 Uhr (UTC+2)<\/strong> bieten wir dir die M\u00f6glichkeit, mit einer Rendite von 10,5 % in 12 Monaten zu investieren. Hier ist alles, was du wissen musst.<\/p>\n\n<p>Dieses Mal kehren wir in die Autonome Gemeinschaft Madrid zur\u00fcck. Das Projekt <a href=\"https:\/\/urbanitae.com\/en\/project\/P000302?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0724&amp;utm_term=los_fresnos_1&amp;utm_content=de_proyecto_los_fresnos\" target=\"_blank\" rel=\"noreferrer noopener\">Los Fresnos<\/a> besteht in der Gew\u00e4hrung eines <strong>Darlehens zur Finanzierung der Kosten f\u00fcr den Erwerb eines Grundst\u00fccks und der st\u00e4dtebaulichen Kosten, die f\u00fcr die Erlangung einer Baugenehmigung f\u00fcr sechs Einfamilienh\u00e4user erforderlich sind.<\/strong> Das Projekt befindet sich in Boadilla del Monte, der drittreichsten Gemeinde Spaniens und der zweitreichsten in der Autonomen Gemeinschaft Madrid. Das Grundst\u00fcck liegt in einer der begehrtesten Wohngegenden von Boadilla.<\/p>\n\n<p>Was den Entwickler betrifft, so ist <a href=\"https:\/\/www.auric-partners.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Auric Partners<\/a> auf solche Projekte spezialisiert. Gegr\u00fcndet im Jahr 2014, liegt der Fokus auf der Immobilienberatung, indem K\u00e4ufer und Verk\u00e4ufer bei wichtigen Immobilientransaktionen, K\u00e4ufen und Akquisitionen, strukturierter Finanzierung und Marktprognosen beraten werden.<\/p>\n\n<h2 class=\"wp-block-heading\">10,5 % Rendite in 12 Monaten<\/h2>\n\n<p>Das Projekt <a href=\"https:\/\/urbanitae.com\/en\/project\/P000302?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0724&amp;utm_term=los_fresnos_2&amp;utm_content=de_proyecto_los_fresnos\" target=\"_blank\" rel=\"noreferrer noopener\">Los Fresnos<\/a> ist ein Schuldenprojekt. Die Investoren von Urbanitae werden dem Entwickler daher ein <strong>Darlehen in H\u00f6he von 1.700.000 Euro<\/strong> gew\u00e4hren. Die Laufzeit des Darlehens betr\u00e4gt 12 Monate, und der Zinssatz ist fest und betr\u00e4gt 10,5 % pro Jahr. Der Beitrag der Urbanitae-Investoren wird zur Finanzierung eines Teils des Kaufpreises, der gesamten Mehrwertsteuer des Kaufs und eines Teils der Kosten f\u00fcr die Aufteilung und Soft Costs des Projekts verwendet.<\/p>\n\n<p>Die vollst\u00e4ndige vorzeitige R\u00fcckzahlung ist jederzeit zul\u00e4ssig, <strong>vorbehaltlich einer garantierten Mindestverzinsung des Darlehens, die 12 Monate Zinsen entspricht.<\/strong> Dar\u00fcber hinaus ist eine Verl\u00e4ngerung um sechs weitere Monate im 12. Monat zul\u00e4ssig.<\/p>\n\n<h2 class=\"wp-block-heading\">Erstrangige Hypothekensicherheit<\/h2>\n\n<p>Wie bei unseren <a href=\"https:\/\/blog.urbanitae.com\/en\/2023\/01\/20\/8-what-are-the-debt-projects-like-crowdlending\/?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0724&amp;utm_term=schuldenprojekten&amp;utm_content=de_proyecto_los_fresnos\" target=\"_blank\" rel=\"noreferrer noopener\">Schuldenprojekten<\/a> \u00fcblich, haben wir strenge Sicherheiten eingerichtet, um die Investition im Falle eines Zahlungsausfalls zu sch\u00fctzen. Konkret sieht der Darlehensvertrag f\u00fcr Los Fresnos eine <strong>Erstrangige Hypothek auf das Grundbuchgrundst\u00fcck vor, auf dem das Projekt entwickelt wird,<\/strong> \u00fcber einen Treuh\u00e4nder. Au\u00dferdem haben wir ein Erstrangpfandrecht auf die Aktien der <a href=\"https:\/\/blog.urbanitae.com\/en\/2023\/02\/19\/9-what-are-spvs\/?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0724&amp;utm_term=spv&amp;utm_content=de_proyecto_los_fresnos\" target=\"_blank\" rel=\"noreferrer noopener\">SPV<\/a> und auf die Bankkonten der SPV festgelegt.<\/p>\n\n<p>Der gesch\u00e4tzte Zeitrahmen des Projekts betr\u00e4gt 12 Monate \u2013 mit einer m\u00f6glichen Verl\u00e4ngerung um sechs Monate im 12. Monat. Somit sieht der Gesch\u00e4ftsplan einen Zeitraum zwischen Juli 2024 und April 2025 f\u00fcr die Einreichung des Teilungsprojekts und die Erlangung der Baugenehmigung vor. Zwischen April und Juli w\u00fcrde der Verkauf der Grundst\u00fccke und die R\u00fcckzahlung des von den Urbanitae-Investoren gew\u00e4hrten Darlehens erfolgen.<\/p>\n\n<p>In diesem Video erkl\u00e4ren der Entwickler und Diego Bestard, CEO von Urbanitae, die Details des Projekts.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-156101d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"156101d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-efe12f1\" data-id=\"efe12f1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08adc96 elementor-widget elementor-widget-video\" data-id=\"08adc96\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/G42LBn3tGig&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-42fbe01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42fbe01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-222d719\" data-id=\"222d719\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1cfea7 elementor-widget elementor-widget-text-editor\" data-id=\"d1cfea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn du Fragen hast, kannst du sie auf unserem <a href=\"https:\/\/t.me\/urbanitaetelegram?utm_source=blog_de&amp;utm_medium=organic&amp;utm_campaign=urbanitae_blog_0724&amp;utm_term=telegram&amp;utm_content=de_proyecto_los_fresnos\" target=\"_blank\" rel=\"noreferrer noopener\">Telegram<\/a>-Kanal stellen, <strong>den wir am Montag, den 15. Juli um 10:00 Uhr (UTC+2) er\u00f6ffnen werden.<\/strong> Wie immer kannst du uns per E-Mail unter <a href=\"mailto:contacto@urbanitae.com\" target=\"_blank\" rel=\"noreferrer noopener\">contacto@urbanitae.com<\/a> und telefonisch unter (+34) 911 23 25 22 erreichen. Verpasse nicht die Gelegenheit, <strong>mit einer Rendite von 10,5 % in 12 Monaten zu investieren.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Wir gew\u00e4hren Auric Partners ein Darlehen zur Finanzierung des Erwerbs eines Grundst\u00fccks und zur Erlangung einer Baugenehmigung f\u00fcr sechs Einfamilienh\u00e4user.<\/p>\n","protected":false},"author":1,"featured_media":46278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[795,1079,1699,929,1700],"tags":[1962,1965,1954,2176,2184],"class_list":["post-46249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deuda","category-divida","category-projekte","category-projetos","category-schulden","tag-crowdfunding-inmobiliario","tag-immobilien-crowdfunding","tag-immobilien-crowdlending","tag-immobilieninvestition","tag-wohnimmobiliensektor"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten - Urbanitae Blog<\/title>\n<meta name=\"description\" content=\"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investiere mit einer Rendite von 10,5% in 12 Monaten\" \/>\n<meta property=\"og:description\" content=\"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T12:53:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T12:54:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten\",\"datePublished\":\"2024-07-12T12:53:22+00:00\",\"dateModified\":\"2024-07-12T12:54:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/\"},\"wordCount\":488,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp\",\"keywords\":[\"crowdfunding inmobiliario\",\"Immobilien Crowdfunding\",\"Immobilien Crowdlending\",\"Immobilieninvestition\",\"Wohnimmobiliensektor\"],\"articleSection\":[\"Deuda\",\"D\u00edvida\",\"Projekte\",\"Projetos\",\"Schulden\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/\",\"name\":\"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten - Urbanitae Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp\",\"datePublished\":\"2024-07-12T12:53:22+00:00\",\"dateModified\":\"2024-07-12T12:54:37+00:00\",\"description\":\"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp\",\"width\":1400,\"height\":735,\"caption\":\"Invierte con un 10,5% de rentabilidad en 12 meses. Invest with a 10.5% return in 12 months.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/07\\\/12\\\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Inversi\u00f3n inmobiliaria al alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten - Urbanitae Blog","description":"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/","og_locale":"de_DE","og_type":"article","og_title":"Investiere mit einer Rendite von 10,5% in 12 Monaten","og_description":"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.","og_url":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/","og_site_name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2024-07-12T12:53:22+00:00","article_modified_time":"2024-07-12T12:54:37+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Verfasst von":"Equipo Urbanitae","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten","datePublished":"2024-07-12T12:53:22+00:00","dateModified":"2024-07-12T12:54:37+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/"},"wordCount":488,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp","keywords":["crowdfunding inmobiliario","Immobilien Crowdfunding","Immobilien Crowdlending","Immobilieninvestition","Wohnimmobiliensektor"],"articleSection":["Deuda","D\u00edvida","Projekte","Projetos","Schulden"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/","url":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/","name":"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten - Urbanitae Blog","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp","datePublished":"2024-07-12T12:53:22+00:00","dateModified":"2024-07-12T12:54:37+00:00","description":"Wir geben dir die Gelegenheit, in ein Immobilienprojekt in Madrid mit einer Rendite von 10,5% in 12 Monaten zu investieren. Lies mehr.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/07\/invierte-rentabilidad-12-meses-urbanitae-los-fresnos.webp","width":1400,"height":735,"caption":"Invierte con un 10,5% de rentabilidad en 12 meses. Invest with a 10.5% return in 12 months."},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/07\/12\/investieren-sie-mit-einer-rendite-von-105-in-12-monaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/de\/"},{"@type":"ListItem","position":2,"name":"Neues Projekt! Investieren Sie mit einer Rendite von 10,5\u00a0% in 12 Monaten"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/de\/#website","url":"https:\/\/blog.urbanitae.com\/de\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Inversi\u00f3n inmobiliaria al alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/de\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/de\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/46249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/comments?post=46249"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/46249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media\/46278"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media?parent=46249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/categories?post=46249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/tags?post=46249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}