{"id":42110,"date":"2024-05-17T12:43:54","date_gmt":"2024-05-17T10:43:54","guid":{"rendered":"https:\/\/blog.urbanitae.com\/?p=42110"},"modified":"2024-05-18T00:26:17","modified_gmt":"2024-05-17T22:26:17","slug":"wie-schutzt-urbanitae-das-geld-seiner-investoren","status":"publish","type":"post","link":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/","title":{"rendered":"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Immobiliensektor gilt als sicherer Hafen f\u00fcr Investitionen. Aber das bedeutet nicht, dass keine Risiken bestehen. In diesem Artikel erkl\u00e4ren wir, wie wir bei Urbanitae die Risiken minimieren und vor allem, wie wir das von unseren Investoren bereitgestellte Kapital so gut wie m\u00f6glich absichern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die erste Strategie ist grundlegend: Wir versuchen, <a href=\"https:\/\/blog.urbanitae.com\/de\/2023\/07\/09\/wie-waehlt-urbanitae-die-projekte-aus-die-es-finanziert\/\" target=\"_blank\" rel=\"noreferrer noopener\">gute Projekte<\/a> auszuw\u00e4hlen<\/strong>. Diese Auswahl beginnt mit dem Bautr\u00e4ger, von dem wir eine nachweisbare Erfolgsbilanz verlangen, die belegt, dass er in der Lage ist, ein Projekt wie das vorgeschlagene durchzuf\u00fchren. Es folgt eine sorgf\u00e4ltige Bewertung der Annahmen des Gesch\u00e4ftsplans, die Validierung dieser Annahmen und die Festlegung von Bedingungen zum Schutz des Geldes unserer Investoren.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Das Grundst\u00fcck, die wichtigste Garantie<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In einem Immobilienprojekt wie denen, die wir bei Urbanitae finanzieren, ist das Grundst\u00fcck die Hauptgarantie. Die von unseren Investoren bereitgestellten Mittel in <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/02\/21\/wie-sind-die-wertsteigerungsprojekte-bei-urbanitae\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wertsteigerungsprojekten<\/a> werden haupts\u00e4chlich f\u00fcr den Kauf des Grundst\u00fccks verwendet. <strong>Die Realit\u00e4t ist, dass das Endgrundst\u00fcck in guten Lagen dazu neigt, seinen Wert nicht nur zu halten, sondern zu steigern<\/strong>. Daher k\u00f6nnte das Grundst\u00fcck, wenn es zum Marktwert gekauft wurde, verkauft werden, um die Investition \u2013 sogar mit Gewinn \u2013 zur\u00fcckzuerhalten, falls das Projekt nicht wie erwartet verl\u00e4uft. Diese Garantie, die mit dem Wert des Verm\u00f6genswerts verbunden ist, auf den die Investition get\u00e4tigt wird, l\u00e4sst die Investoren von Urbanitae ruhig schlafen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Eine SPV f\u00fcr jedes Projekt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein weiterer wichtiger Punkt ist, dass jedes Projekt zu 100 % unabh\u00e4ngig von den anderen ist, sodass es keinen Ansteckungseffekt geben kann, falls eines von ihnen nicht gut verl\u00e4uft. Die Mittel der Investoren, die vor der Investition auf einem Konto in ihrem Namen \u2013 und niemals auf einem Konto von Urbanitae \u2013 liegen, werden auf das Projektkonto und von dort auf das laufende Konto der Betriebsgesellschaft \u00fcberwiesen, sei es als Darlehen oder als Kapitalerh\u00f6hung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus finanzieren wir die <a href=\"https:\/\/blog.urbanitae.com\/en\/2023\/02\/19\/9-what-are-spvs\/\" target=\"_blank\" rel=\"noreferrer noopener\">SPV<\/a>, die Eigent\u00fcmerin des Verm\u00f6genswerts\/Projekts ist. <strong>Indem wir nicht direkt den Bautr\u00e4ger finanzieren, vermeiden wir jegliches Bilanzrisiko<\/strong> im Zusammenhang mit bestehenden Verpflichtungen oder Verbindlichkeiten der Aktivit\u00e4ten des Bautr\u00e4gers und seiner Gesellschaft. In den Schuldprojekten erh\u00e4lt der Bautr\u00e4ger zudem nicht die gesamten Mittel von Anfang an, sondern greift auf das Kapital je nach Baufortschritt zu \u2013 obwohl er Zinsen auf das gesamte aufgebrachte Kapital zahlen muss, auch wenn er es noch nicht verwendet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u2018Skin in the game\u2019 des Bautr\u00e4gers<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In den Projekten von <a href=\"https:\/\/urbanitae.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">Urbanitae<\/a> fordern wir, mit wenigen begr\u00fcndeten Ausnahmen, <strong>dass der Bautr\u00e4ger mindestens 20 % des Eigenkapitals beisteuert<\/strong>. Dieses Kapital wird zu denselben Bedingungen wie das der anderen Investoren verg\u00fctet \u2013 obwohl manchmal eine zus\u00e4tzliche Pr\u00e4mie oder Provision vereinbart werden kann, wenn das Projekt eine bestimmte Renditeschwelle f\u00fcr das investierte Kapital \u00fcberschreitet. Das hei\u00dft, wenn das Projekt scheitert, ist der Bautr\u00e4ger auch direkt betroffen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Konservativer Gesch\u00e4ftsplan<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um ein Projekt zu genehmigen, f\u00fchrt unser Investmentkomitee eine strenge Due Diligence des Gesch\u00e4ftsplans des Bautr\u00e4gers durch. Das bedeutet, dass die Beziehung des Bautr\u00e4gers zu den Banken und sein Zugang zu Finanzierungen, die Verkaufspreise \u2013 die von Dritten validiert werden, dass sie f\u00fcr das Produkt und die Region angemessen sind \u2013 sowie die Baukosten \u00fcberpr\u00fcft werden. <strong>Im Gesch\u00e4ftsplan, den wir den Investoren pr\u00e4sentieren, f\u00fcgen wir in der Regel eine Sicherheitsmarge<\/strong> in Form h\u00f6herer Baukosten und niedrigerer Durchschnittsverkaufspreise hinzu, um m\u00f6gliche Abweichungen aufzufangen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Garantien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das Garantieniveau unserer Darlehen ist sehr hoch: In <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/02\/21\/wie-sind-die-wertsteigerungsprojekte-bei-urbanitae\/\" target=\"_blank\" rel=\"noreferrer noopener\">Wertsteigerungsprojekten<\/a> sind die Investoren von Urbanitae Aktion\u00e4re und somit Eigent\u00fcmer des Unternehmens. In <a href=\"https:\/\/blog.urbanitae.com\/en\/2023\/01\/20\/8-what-are-the-debt-projects-like-crowdlending\/\" target=\"_blank\" rel=\"noreferrer noopener\">Schuldprojekten<\/a> haben die Investoren \u00fcber die Garantieagenten Hypotheken auf den Verm\u00f6genswert und Pfandrechte an den Aktien des Unternehmens. Im Falle eines Zahlungsausfalls w\u00fcrden die Investoren von Urbanitae somit ebenfalls Eigent\u00fcmer der Aktien sowie Hypothekengl\u00e4ubiger ersten Ranges auf den Verm\u00f6genswert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das hei\u00dft, im Falle eines Zahlungsausfalls des Darlehens k\u00f6nnen wir die Hypothek durchsetzen, das Eigentum am Verm\u00f6genswert erwerben und es verkaufen, um die Schuld \u2013 Kapital plus Zinsen \u2013 zur\u00fcckzuerhalten. Alle Kosten (Kosten und R\u00fcckstellung des Garantieagenten, Kosten f\u00fcr die Eintragung der Hypothek, Anwaltskosten usw.) werden vom Bautr\u00e4ger \u2013 Schuldner \u2013 getragen und sind zus\u00e4tzlich zu den an die Investoren\/Kreditgeber zu zahlenden Zinsen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Und bei Mietprojekten?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Bei <a href=\"https:\/\/blog.urbanitae.com\/de\/2024\/01\/18\/wie-man-von-mieteinnahmen-durch-immobilieninvestitionen-leben-kann\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mietprojekten<\/a> gibt es neben dem Eigentum am Verm\u00f6genswert einen langfristigen Vertrag mit einem solventen Mieter \u2013 in der Regel zwei bis drei Jahre \u2013 der zumindest in den ersten Jahren die Zahlung <strong>der Miete garantiert, auch wenn das Gesch\u00e4ft nicht funktioniert und die R\u00e4umlichkeiten verlassen werden<\/strong>. Aber dieser Vertrag ist nicht die einzige Garantie. Wir analysieren detailliert den Immobilienwert des Verm\u00f6genswerts, das hei\u00dft, seinen Marktwert im Leerstand, was uns sagt, ob es im unwahrscheinlichen Fall, dass der aktuelle Mieter das Gesch\u00e4ft aufgibt, m\u00f6glich sein wird, einen anderen Mieter mit \u00e4hnlicher Miete zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Bautr\u00e4ger ist das wesentliche Element, damit alles funktioniert. Dar\u00fcber hinaus setzen wir Garantien, um das Anlegerrisiko zu minimieren.<\/p>\n","protected":false},"author":1,"featured_media":42099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1714],"tags":[2177,2176,1745],"class_list":["post-42110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urbanitae-de","tag-alternative-investmentanlage","tag-immobilieninvestition","tag-urbanitae-de"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie sch\u00fctzt Urbanitae das Geld seiner Investoren? - Urbanitae Blog<\/title>\n<meta name=\"description\" content=\"F\u00fcr Urbanitae ist die Sicherheit des Geldes der Investoren von entscheidender Bedeutung. Wir erkl\u00e4ren, wie wir die Investition sch\u00fctzen und unvorhergesehene Ereignisse bew\u00e4ltigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Immobilienbereich ist das Grundst\u00fcck die beste Garantie\" \/>\n<meta property=\"og:description\" content=\"Ein fertig erschlossenes Grundst\u00fcck in guter Lage ist die beste Garantie, wenn es um Immobilieninvestitionen geht. Aber es ist nicht die einzige. Wir erkl\u00e4ren, wie wir das bei Urbanitae machen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/\" \/>\n<meta property=\"og:site_name\" content=\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/urbanitae\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-17T10:43:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-17T22:26:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"735\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Urbanitae\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:site\" content=\"@urbanitae\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Urbanitae\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/\"},\"author\":{\"name\":\"Equipo Urbanitae\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\"},\"headline\":\"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren?\",\"datePublished\":\"2024-05-17T10:43:54+00:00\",\"dateModified\":\"2024-05-17T22:26:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/\"},\"wordCount\":814,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/urbanitae-dinero-inversores.webp\",\"keywords\":[\"alternative Investmentanlage\",\"Immobilieninvestition\",\"Urbanitae\"],\"articleSection\":[\"Urbanitae\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/\",\"name\":\"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren? - Urbanitae Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/urbanitae-dinero-inversores.webp\",\"datePublished\":\"2024-05-17T10:43:54+00:00\",\"dateModified\":\"2024-05-17T22:26:17+00:00\",\"description\":\"F\u00fcr Urbanitae ist die Sicherheit des Geldes der Investoren von entscheidender Bedeutung. Wir erkl\u00e4ren, wie wir die Investition sch\u00fctzen und unvorhergesehene Ereignisse bew\u00e4ltigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/urbanitae-dinero-inversores.webp\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/urbanitae-dinero-inversores.webp\",\"width\":1400,\"height\":735,\"caption\":\"Urbanitae protege el dinero de los inversores con la selecci\u00f3n rigurosa de los proyectos y la fijaci\u00f3n de garant\u00edas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/2024\\\/05\\\/17\\\/wie-schutzt-urbanitae-das-geld-seiner-investoren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"name\":\"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria\",\"description\":\"Inversi\u00f3n inmobiliaria al alcance de todos\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#organization\",\"name\":\"Urbanitae\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"contentUrl\":\"https:\\\/\\\/blog.urbanitae.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/logo-verde_350x100.svg\",\"width\":350,\"height\":100,\"caption\":\"Urbanitae\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/urbanitae\",\"https:\\\/\\\/x.com\\\/urbanitae\",\"https:\\\/\\\/www.instagram.com\\\/urbanitae\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/urbanitae\",\"https:\\\/\\\/www.pinterest.es\\\/UrbanitaeSL\\\/_created\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/Urbanitae_RE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/#\\\/schema\\\/person\\\/e7b2d152f5654066832c53f5aa04fbf7\",\"name\":\"Equipo Urbanitae\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g\",\"caption\":\"Equipo Urbanitae\"},\"sameAs\":[\"https:\\\/\\\/urbanitae.com\"],\"url\":\"https:\\\/\\\/blog.urbanitae.com\\\/de\\\/author\\\/urbanitae\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren? - Urbanitae Blog","description":"F\u00fcr Urbanitae ist die Sicherheit des Geldes der Investoren von entscheidender Bedeutung. Wir erkl\u00e4ren, wie wir die Investition sch\u00fctzen und unvorhergesehene Ereignisse bew\u00e4ltigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/","og_locale":"de_DE","og_type":"article","og_title":"Im Immobilienbereich ist das Grundst\u00fcck die beste Garantie","og_description":"Ein fertig erschlossenes Grundst\u00fcck in guter Lage ist die beste Garantie, wenn es um Immobilieninvestitionen geht. Aber es ist nicht die einzige. Wir erkl\u00e4ren, wie wir das bei Urbanitae machen.","og_url":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/","og_site_name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","article_publisher":"https:\/\/www.facebook.com\/urbanitae","article_published_time":"2024-05-17T10:43:54+00:00","article_modified_time":"2024-05-17T22:26:17+00:00","og_image":[{"width":1400,"height":735,"url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp","type":"image\/webp"}],"author":"Equipo Urbanitae","twitter_card":"summary_large_image","twitter_creator":"@urbanitae","twitter_site":"@urbanitae","twitter_misc":{"Verfasst von":"Equipo Urbanitae","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#article","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/"},"author":{"name":"Equipo Urbanitae","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7"},"headline":"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren?","datePublished":"2024-05-17T10:43:54+00:00","dateModified":"2024-05-17T22:26:17+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/"},"wordCount":814,"commentCount":0,"publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp","keywords":["alternative Investmentanlage","Immobilieninvestition","Urbanitae"],"articleSection":["Urbanitae"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/","url":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/","name":"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren? - Urbanitae Blog","isPartOf":{"@id":"https:\/\/blog.urbanitae.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#primaryimage"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp","datePublished":"2024-05-17T10:43:54+00:00","dateModified":"2024-05-17T22:26:17+00:00","description":"F\u00fcr Urbanitae ist die Sicherheit des Geldes der Investoren von entscheidender Bedeutung. Wir erkl\u00e4ren, wie wir die Investition sch\u00fctzen und unvorhergesehene Ereignisse bew\u00e4ltigen.","breadcrumb":{"@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#primaryimage","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2024\/05\/urbanitae-dinero-inversores.webp","width":1400,"height":735,"caption":"Urbanitae protege el dinero de los inversores con la selecci\u00f3n rigurosa de los proyectos y la fijaci\u00f3n de garant\u00edas"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.urbanitae.com\/de\/2024\/05\/17\/wie-schutzt-urbanitae-das-geld-seiner-investoren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/blog.urbanitae.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wie sch\u00fctzt Urbanitae das Geld seiner Investoren?"}]},{"@type":"WebSite","@id":"https:\/\/blog.urbanitae.com\/de\/#website","url":"https:\/\/blog.urbanitae.com\/de\/","name":"Urbanitae Blog | Las mejores noticias sobre inversi\u00f3n inmobiliaria","description":"Inversi\u00f3n inmobiliaria al alcance de todos","publisher":{"@id":"https:\/\/blog.urbanitae.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.urbanitae.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.urbanitae.com\/de\/#organization","name":"Urbanitae","url":"https:\/\/blog.urbanitae.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","contentUrl":"https:\/\/blog.urbanitae.com\/wp-content\/uploads\/2020\/04\/logo-verde_350x100.svg","width":350,"height":100,"caption":"Urbanitae"},"image":{"@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/urbanitae","https:\/\/x.com\/urbanitae","https:\/\/www.instagram.com\/urbanitae","https:\/\/www.linkedin.com\/company\/urbanitae","https:\/\/www.pinterest.es\/UrbanitaeSL\/_created\/","https:\/\/www.youtube.com\/c\/Urbanitae_RE"]},{"@type":"Person","@id":"https:\/\/blog.urbanitae.com\/de\/#\/schema\/person\/e7b2d152f5654066832c53f5aa04fbf7","name":"Equipo Urbanitae","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e75782c6aa253c8ac75c13b1ec97172bb2d67437baa4354ba4b0650a97f565f2?s=96&d=mm&r=g","caption":"Equipo Urbanitae"},"sameAs":["https:\/\/urbanitae.com"],"url":"https:\/\/blog.urbanitae.com\/de\/author\/urbanitae\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/42110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/comments?post=42110"}],"version-history":[{"count":0,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/posts\/42110\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media\/42099"}],"wp:attachment":[{"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/media?parent=42110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/categories?post=42110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.urbanitae.com\/de\/wp-json\/wp\/v2\/tags?post=42110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}